{"id":872,"date":"2018-12-12T21:11:00","date_gmt":"2018-12-12T23:11:00","guid":{"rendered":"http:\/\/vipfesta.com.br\/vipfesta\/?p=872"},"modified":"2020-01-07T08:29:15","modified_gmt":"2020-01-07T11:29:15","slug":"livro-de-design-com-pecas-de-artesaos","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/livro-de-design-com-pecas-de-artesaos\/","title":{"rendered":"Livro de Design com pe\u00e7as de artes\u00e3os rondonienses \u00e9 lan\u00e7ado no Rio de janeiro"},"content":{"rendered":"<p><a href=\"https:\/\/4.bp.blogspot.com\/-yE4yaRiC5r8\/XBFMUBkW3mI\/AAAAAAAGN60\/oOGCQ07iu5IzxbnqWnzhbOsou8AoolnNwCKgBGAs\/s1600\/Raizes05.jpg\" imageanchor=\"1\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"560\" data-original-width=\"1152\" height=\"155\" src=\"http:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2018\/12\/Raizes05.jpg\" width=\"320\" \/><\/a>O Centro Sebrae de Refer\u00eancia do Artesanato Brasileiro (Crab), na cidade do Rio de de Janeiro, foi palco do lan\u00e7amento do livro Ra\u00edzes Amaz\u00f4nicas \u2013 Arte &amp; Design de Rond\u00f4nia no ultimo fim de semana(06 e 07). A publica\u00e7\u00e3o \u00e9 uma iniciativa do Sebrae em Rond\u00f4nia, em parceria com o pr\u00f3prio Crab e com curadoria do Ar\u00e1 Studio e re\u00fane obras e hist\u00f3rias de artes\u00e3os de Rond\u00f4nia que expressam a pluralidade amaz\u00f4nica em formas, cores e texturas a partir de pe\u00e7as feitas em materiais como madeira, cer\u00e2mica, acr\u00edlico aliados a t\u00e9cnicas de bordados e pintura em tecido.<\/p>\n<p><a href=\"https:\/\/4.bp.blogspot.com\/-4lzJMf0MMJU\/XBFMcr6928I\/AAAAAAAGN64\/CCoSoVJ3ZwwMGV92awpyG0TTglDsri9IwCKgBGAs\/s1600\/Raizes06.jpg\" imageanchor=\"1\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"560\" data-original-width=\"1152\" height=\"96\" src=\"http:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2018\/12\/Raizes06.jpg\" width=\"200\" \/><\/a>A a\u00e7\u00e3o \u00e9 uma estrat\u00e9gia de busca de novos mercados e prospec\u00e7\u00e3o de potenciais clientes que procuram pe\u00e7as com qualidade no acabamento, tenham possibilidade de produ\u00e7\u00e3o em escala e que contem hist\u00f3rias amaz\u00f4nicas, traduzindo os saberes e fazeres desta regi\u00e3o brasileira, rica culturalmente.<\/p>\n<p><a href=\"https:\/\/2.bp.blogspot.com\/-_X6qjVNnhYo\/XBFMcrbuHlI\/AAAAAAAGN64\/44w5R_qHEZ41OnsnWYt9lKmOWmwfedz1QCKgBGAs\/s1600\/Raizes07.jpg\" imageanchor=\"1\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"560\" data-original-width=\"1152\" height=\"96\" src=\"http:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2018\/12\/Raizes07.jpg\" width=\"200\" \/><\/a>O Centro Sebrae de Refer\u00eancia do Artesanato Brasileiro (Crab), na cidade do Rio de de Janeiro, foi palco do lan\u00e7amento do livro Ra\u00edzes Amaz\u00f4nicas \u2013 Arte &amp; Design de Rond\u00f4nia no ultimo fim de semana(06 e 07). A publica\u00e7\u00e3o \u00e9 uma iniciativa do Sebrae em Rond\u00f4nia, em parceria com o pr\u00f3prio Crab e com curadoria do Ar\u00e1 Studio e re\u00fane obras e hist\u00f3rias de artes\u00e3os de Rond\u00f4nia que expressam a pluralidade amaz\u00f4nica em formas, cores e texturas a partir de pe\u00e7as feitas em materiais como madeira, cer\u00e2mica, acr\u00edlico aliados a t\u00e9cnicas de bordados e pintura em tecido.<\/p>\n<p><a href=\"https:\/\/1.bp.blogspot.com\/-ePpZfeMYlTk\/XBFL8n3jIpI\/AAAAAAAGN6s\/0N7s-uYTn38V-gtoJkn8cC7xqPK08DTuQCKgBGAs\/s1600\/Raizes04.jpg\" imageanchor=\"1\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"560\" data-original-width=\"1152\" height=\"96\" src=\"http:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2018\/12\/Raizes04.jpg\" width=\"200\" \/><\/a>A a\u00e7\u00e3o \u00e9 uma estrat\u00e9gia de busca de novos mercados e prospec\u00e7\u00e3o de potenciais clientes que procuram pe\u00e7as com qualidade no acabamento, tenham possibilidade de produ\u00e7\u00e3o em escala e que contem hist\u00f3rias amaz\u00f4nicas, traduzindo os saberes e fazeres desta regi\u00e3o brasileira, rica culturalmente.<\/p>\n<p><a href=\"https:\/\/2.bp.blogspot.com\/-ZlVnoPGmK3E\/XBFMcpzRqNI\/AAAAAAAGN64\/J8Ge2UCDieAnU5uGyvthmlPwWSdP7vFCgCKgBGAs\/s1600\/Raizes08.jpg\" imageanchor=\"1\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"1152\" data-original-width=\"560\" height=\"200\" src=\"http:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2018\/12\/Raizes08.jpg\" width=\"96\" \/><\/a>O evento levou ao pr\u00e9dio hist\u00f3rico na pra\u00e7a Tiradentes, centro da Cidade Maravilhosa, um p\u00fablico especializado em design de objetos, arquitetura e decora\u00e7\u00e3o que j\u00e1 na oportunidade conheceram e at\u00e9 adquiriram algumas das pe\u00e7as ali expostas, al\u00e9m de apreciar a compila\u00e7\u00e3o da produ\u00e7\u00e3o artesanal de Rond\u00f4nia documentada a partir a parceria do Sebrae em Rond\u00f4nia e do Ar\u00e1 Studio.<\/p>\n<p>Heliana Marinho, diretora do CRAB, destacou a import\u00e2ncia simb\u00f3lica deste lan\u00e7amento no Rio de Janeiro: \u201cO CRAB pretende, atrav\u00e9s de exposi\u00e7\u00f5es, lan\u00e7amentos de livros e debates, fazer uma requalifica\u00e7\u00e3o do artesanato brasileiro. \u00c9 trazer, dar visibilidade e apresentar para o mundo um artesanato diferenciado. Aqui, al\u00e9m dos espa\u00e7os de exposi\u00e7\u00f5es e oportunidades de lan\u00e7ar cat\u00e1logos como este de Rond\u00f4nia, temos uma \u00e1rea que trabalha a comercializa\u00e7\u00e3o destes produtos.\u201d<\/p>\n<p>Convidados conheceram pe\u00e7as de design e trocaram experi\u00eancias enquanto um coquetel bem regional era servido aos presentes. O Diretor T\u00e9cnico do Sebrae em Rond\u00f4nia, Samuel Silva de Almeida, comentou sobre a a\u00e7\u00e3o: \u201c\u00c9 uma iniciativa fundamental para a promo\u00e7\u00e3o de uma arte rondoniense que tem ra\u00edzes regionalizadas na nossa Amaz\u00f4nia, com pessoas empreendedoras que ali promovem seu crescimento literalmente atrav\u00e9s de suas pr\u00f3prias m\u00e3os\u201d.<\/p>\n<p>Ezequiel Candioto, artes\u00e3o de Rond\u00f4nia, estabelecido na cidade de Ariquemes, comemora a oportunidade: \u201cMeu trabalho \u00e9 inspirado no que Rond\u00f4nia produz, nas frutas regionais, os peixes da Amaz\u00f4nia. E neste livro apresenta como de minha autoria um puff, uma cadeira, as frutas e a bandeja, todos esculpidos em madeira. Minha rela\u00e7\u00e3o com o Sebrae \u00e9 de muitos anos, j\u00e1 fiz outras exposi\u00e7\u00f5es junto ao Sebrae\u201d, contou ele, que desenvolve pe\u00e7as em madeira e marchetaria. Todos os artes\u00e3os presentes receberam elogios dos visitantes e, em especial, dos t\u00e9cnicos do Crab.<\/p>\n<p>O Sebrae em Rond\u00f4nia acredita que iniciativas como a publica\u00e7\u00e3o deste livro contribuem para agregar valor aos produtos regionais de Rond\u00f4nia e fomentar o desenvolvimento deste importante gerador de renda que \u00e9 a Economia Criativa. Foi desenvolvido um trabalho cuidadoso na produ\u00e7\u00e3o e curadoria de escolha de pe\u00e7as, baseados em crit\u00e9rios tanto t\u00e9cnicos como art\u00edsticos, uma vez que o Crab confere uma verdadeira chancela de qualidade a qualquer produto, por esta raz\u00e3o foi o local definido para o lan\u00e7amento da publica\u00e7\u00e3o.<\/p>\n<p>Para viabilizar esta iniciativa, foram firmadas parcerias estrat\u00e9gicas &#8211; al\u00e9m do pr\u00f3prio Crab, que recepcionou em grande estilo a arte rondoniense, o trabalho de curadoria ficou a cargo do Ar\u00e1 Studio: \u201cNossa empresa \u00e9 genuinamente Amaz\u00f4nica, fomentando e desenvolvendo pe\u00e7as autorais que tenham grande potencial para figurar nas prateleiras especializadas mais qualificadas do Brasil e at\u00e9 do mundo. Encontramos no Sebrae um grande apoiador para gerar, no m\u00ednimo, expectativas de grandes neg\u00f3cios num futuro pr\u00f3ximo, por isso tivemos tanto cuidado na curadoria deste cat\u00e1logo \u201c comemorou o designer Jos\u00e9 Ocanha, um dos curadores da publica\u00e7\u00e3o.<\/p>\n<p>As pe\u00e7as que n\u00e3o foram comercializadas (foram apenas dois dias no concorrido Crab) estar\u00e3o no estoque da prestigiada e exclusiva loja da casa, anexa ao Crab, unindo-se a pe\u00e7as de todo o Brasil.<\/p>\n<p>Para saber mais sobre essa e outras a\u00e7\u00f5es do Sebrae em Rond\u00f4nia, acesse <a href=\"http:\/\/www.sebrae.ro\/\" target=\"_blank\" rel=\"noopener\">www.sebrae.ro<\/a> ou ligue gratuitamente para a Central de Relacionamento pelo 080 570 0800. Voc\u00ea tamb\u00e9m pode nos acessar pelo n\u00famero de WhatsApp (69) 98130 5656 ou pelas plataformas Instagram, Facebook, Twitter, LinkedIn e YouTube, no perfil Sebrae RO.<\/p>\n<p>\nSebrae\/RO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Centro Sebrae de Refer\u00eancia do Artesanato Brasileiro (Crab), na cidade do Rio de de Janeiro, foi palco do lan\u00e7amento<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[15,23],"class_list":["post-872","post","type-post","status-publish","format-standard","hentry","category-news","tag-cidades","tag-sebrae"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=872"}],"version-history":[{"count":1,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/872\/revisions"}],"predecessor-version":[{"id":20177,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/872\/revisions\/20177"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}