{"id":51021,"date":"2024-08-29T23:29:57","date_gmt":"2024-08-30T03:29:57","guid":{"rendered":"https:\/\/vipfesta.com.br\/vipfesta\/?p=51021"},"modified":"2024-08-29T23:32:23","modified_gmt":"2024-08-30T03:32:23","slug":"esgotamento-7","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/esgotamento-7\/","title":{"rendered":"Obras do Sistema de Esgotamento Sanit\u00e1rio avan\u00e7am no munic\u00edpio de Ji-Paran\u00e1"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2024\/08\/21.06.24_Lagoas-ETE-JI-Parana_Bruno-Motoyama.02-1536x864-1-1024x576.jpg\" alt=\"\" class=\"wp-image-51022\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2024\/08\/21.06.24_Lagoas-ETE-JI-Parana_Bruno-Motoyama.02-1536x864-1-1024x576.jpg 1024w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2024\/08\/21.06.24_Lagoas-ETE-JI-Parana_Bruno-Motoyama.02-1536x864-1-300x169.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2024\/08\/21.06.24_Lagoas-ETE-JI-Parana_Bruno-Motoyama.02-1536x864-1-768x432.jpg 768w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2024\/08\/21.06.24_Lagoas-ETE-JI-Parana_Bruno-Motoyama.02-1536x864-1-150x84.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2024\/08\/21.06.24_Lagoas-ETE-JI-Parana_Bruno-Motoyama.02-1536x864-1.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em><strong>Constru\u00e7\u00e3o das oito lagoas de tratamento de esgoto est\u00e1 sendo executada em uma \u00e1rea de 50 hectares<\/strong><\/em><\/figcaption><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>A<\/strong>s obras do Sistema de Esgotamento Sanit\u00e1rio seguem avan\u00e7ando no munic\u00edpio de Ji-Paran\u00e1, financiadas pelo governo federal, por meio do Programa de Acelera\u00e7\u00e3o do Crescimento (PAC) e gerenciadas pela Secretaria de Estado de Obras e Servi\u00e7os P\u00fablicos (Seosp), as obras registram cerca de 50% de execu\u00e7\u00e3o.<\/p>\n<\/blockquote>\n\n\n\n<p>O progresso dessas obras faz parte do trabalho do governo de Rond\u00f4nia para melhorar o sistema de esgotamento sanit\u00e1rio do munic\u00edpio. Pois o sistema de esgoto engloba toda a parte de capta\u00e7\u00e3o do esgoto sanit\u00e1rio nos bairros at\u00e9 a chegada \u00e0 Esta\u00e7\u00e3o de Tratamento de Esgoto (ETE), onde ocorrer\u00e1 o processo de tratamento desse material, uma obra completa que vai beneficiar e promover sa\u00fade p\u00fablica aos ji-paranaenses.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2024\/08\/28.08.24_Sistema-de-esgotamento-sanitario-Parana_Bruno-Motoyama-768x512-1.jpg\" alt=\"\" class=\"wp-image-51024\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2024\/08\/28.08.24_Sistema-de-esgotamento-sanitario-Parana_Bruno-Motoyama-768x512-1.jpg 768w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2024\/08\/28.08.24_Sistema-de-esgotamento-sanitario-Parana_Bruno-Motoyama-768x512-1-300x200.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2024\/08\/28.08.24_Sistema-de-esgotamento-sanitario-Parana_Bruno-Motoyama-768x512-1-150x100.jpg 150w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Ji-Paran\u00e1 conta com 175 quil\u00f4metros de rede coletora instalada<\/figcaption><\/figure>\n\n\n\n<p id=\"caption-attachment-799295\"><\/p>\n\n\n\n<p>Para o governador de Rond\u00f4nia, Marcos Rocha, as obras do Sistema de Esgotamento Sanit\u00e1rio de Ji-Paran\u00e1 n\u00e3o s\u00e3o apenas uma quest\u00e3o de infraestrutura, mas de sa\u00fade p\u00fablica e preserva\u00e7\u00e3o ambiental.<\/p>\n\n\n\n<p><strong>INVESTIMENTO<\/strong><\/p>\n\n\n\n<p>Or\u00e7adas em R$ 161 milh\u00f5es, as obras do Sistema de Esgotamento Sanit\u00e1rio de Ji-Paran\u00e1 s\u00e3o financiadas por recursos do governo federal, atrav\u00e9s do PAC, com contrapartida do governo do estado. Esse investimento est\u00e1 sendo transformado em mais sa\u00fade e qualidade de vida aos jiparanaenses.<\/p>\n\n\n\n<p><strong>IMPLANTA\u00c7\u00c3O DA REDE COLETORA<\/strong><\/p>\n\n\n\n<p>Uma das principais frentes de trabalho do Sistema de Esgotamento Sanit\u00e1rio \u00e9 a implanta\u00e7\u00e3o da rede coletora de esgoto, com 175.279,10 metros de tubula\u00e7\u00e3o j\u00e1 instaladas. A meta \u00e9 instalar aproximadamente 311 quil\u00f4metros de rede coletora no per\u00edmetro urbano de Ji-Paran\u00e1. Al\u00e9m disso, o projeto prev\u00ea a realiza\u00e7\u00e3o de 26.142 liga\u00e7\u00f5es domiciliares, das quais 14.052 foram conclu\u00eddas.<\/p>\n\n\n\n<p><strong>CONSTRU\u00c7\u00c3O DAS LAGOAS DE TRATAMENTO<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2024\/08\/28.08.24_Sistema-de-esgotamento-sanitario-Parana_Bruno-Motoyama-1-768x432-1.jpg\" alt=\"\" class=\"wp-image-51026\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2024\/08\/28.08.24_Sistema-de-esgotamento-sanitario-Parana_Bruno-Motoyama-1-768x432-1.jpg 768w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2024\/08\/28.08.24_Sistema-de-esgotamento-sanitario-Parana_Bruno-Motoyama-1-768x432-1-300x169.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2024\/08\/28.08.24_Sistema-de-esgotamento-sanitario-Parana_Bruno-Motoyama-1-768x432-1-150x84.jpg 150w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Instala\u00e7\u00e3o da manta termopl\u00e1stica na ETE<\/figcaption><\/figure>\n\n\n\n<p>Paralelamente \u00e0 instala\u00e7\u00e3o da rede coletora, est\u00e1 em andamento a constru\u00e7\u00e3o de oito lagoas de tratamento de esgoto em uma \u00e1rea de 50 hectares. Os servi\u00e7os est\u00e3o focados na instala\u00e7\u00e3o da manta termopl\u00e1stica. Uma vez conclu\u00eddas, essas lagoas desempenhar\u00e3o um papel essencial no tratamento adequado do esgoto, contribuindo para a preserva\u00e7\u00e3o ambiental e melhoria da qualidade da \u00e1gua na regi\u00e3o.<\/p>\n\n\n\n<p>O secret\u00e1rio da Seosp, Elias Rezende, enfatizou a relev\u00e2ncia das obras ao munic\u00edpio. \u201cEssas obras s\u00e3o um registro para Ji-Paran\u00e1. Saneamento \u00e9 fundamental, uma realidade que, com as obras de esgotamento sanit\u00e1rio em andamento assistir\u00e1 \u00e0 popula\u00e7\u00e3o com tratamento de esgoto\u201d,afirmou <\/p>\n\n\n\n<p>Secom)Texto: Bruna Farias<br>Fotos: Bruno Motoyama<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As obras do Sistema de Esgotamento Sanit\u00e1rio seguem avan\u00e7ando no munic\u00edpio de Ji-Paran\u00e1, financiadas pelo governo federal, por meio do<\/p>\n","protected":false},"author":1,"featured_media":51022,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[1148],"class_list":["post-51021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-esgotamento-sanitario"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/51021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=51021"}],"version-history":[{"count":2,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/51021\/revisions"}],"predecessor-version":[{"id":51027,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/51021\/revisions\/51027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/51022"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=51021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=51021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=51021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}