{"id":47922,"date":"2023-12-28T07:22:36","date_gmt":"2023-12-28T11:22:36","guid":{"rendered":"https:\/\/vipfesta.com.br\/vipfesta\/?p=47922"},"modified":"2023-12-28T07:23:58","modified_gmt":"2023-12-28T11:23:58","slug":"deputado-nim-barroso-destina-mais-de-r-16-milhao-para-presidente-medici","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/deputado-nim-barroso-destina-mais-de-r-16-milhao-para-presidente-medici\/","title":{"rendered":"Deputado Nim Barroso destina mais de R$ 1,6 milh\u00e3o para Presidente M\u00e9dici"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/12\/IMG-20231228-WA00492-1024x768.jpg\" alt=\"\" class=\"wp-image-47923\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/12\/IMG-20231228-WA00492-1024x768.jpg 1024w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/12\/IMG-20231228-WA00492-300x225.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/12\/IMG-20231228-WA00492-768x576.jpg 768w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/12\/IMG-20231228-WA00492-150x113.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/12\/IMG-20231228-WA00492.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O deputado Nim Barroso (PSD), na manh\u00e3 desta quarta-feira, 27, anunciou o empenho de emenda parlamentar no valor de R$ 1.603.396,43, para o munic\u00edpio de Presidente M\u00e9dici. O recurso ser\u00e1 utilizado na revitaliza\u00e7\u00e3o da pra\u00e7a municipal.<\/p>\n\n\n\n<p>A pra\u00e7a, ap\u00f3s revitalizada, ter\u00e1 um espa\u00e7o para lazer, com um projeto que inclui paisagismo, local para pr\u00e1tica de exerc\u00edcios, playground e uma pra\u00e7a de alimenta\u00e7\u00e3o.<\/p>\n\n\n\n<p>Para Deivson Bezerra, morador de Presidente M\u00e9dici, a pra\u00e7a \u00e9 um ponto de encontro da grande maioria da popula\u00e7\u00e3o. &#8220;Nossa gente merece um local bem cuidado e bonito. Ser\u00e1 um prazer ver a reforma da pra\u00e7a e o espa\u00e7o voltando a ser utilizado pela nossa popula\u00e7\u00e3o,\u201d destacou. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/12\/IMG-20231228-WA0048-1024x682.jpg\" alt=\"\" class=\"wp-image-47925\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/12\/IMG-20231228-WA0048-1024x682.jpg 1024w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/12\/IMG-20231228-WA0048-300x200.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/12\/IMG-20231228-WA0048-768x512.jpg 768w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/12\/IMG-20231228-WA0048-1536x1023.jpg 1536w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/12\/IMG-20231228-WA0048-150x100.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/12\/IMG-20231228-WA0048.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Conforme o deputado Nim Barroso, a popula\u00e7\u00e3o pediu essa reforma ainda na campanha eleitoral. &#8220;Esse recurso, t\u00e3o solicitado pela comunidade durante a campanha, foi uma das minhas prioridades nesse primeiro ano de mandato e fico muito feliz com o compromisso se tornando realidade,&#8221; concluiu.<\/p>\n\n\n\n<p>Texto: Natalino Ferreira Soares<br>Fotos: Antonio Lucas\/Secom-Ale e Robson Fernandes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado Nim Barroso (PSD), na manh\u00e3 desta quarta-feira, 27, anunciou o empenho de emenda parlamentar no valor de R$<\/p>\n","protected":false},"author":1,"featured_media":47923,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[303],"tags":[1556],"class_list":["post-47922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-nim-barroso"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/47922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=47922"}],"version-history":[{"count":2,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/47922\/revisions"}],"predecessor-version":[{"id":47926,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/47922\/revisions\/47926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/47923"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=47922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=47922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=47922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}