{"id":44170,"date":"2023-06-12T11:18:00","date_gmt":"2023-06-12T15:18:00","guid":{"rendered":"https:\/\/vipfesta.com.br\/vipfesta\/?p=44170"},"modified":"2023-06-12T11:19:23","modified_gmt":"2023-06-12T15:19:23","slug":"silvia-cristina-3","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/silvia-cristina-3\/","title":{"rendered":"Deputada federal S\u00edlvia Cristina participa da posse do gr\u00e3o mestre do Grande Oriente do Brasil em Rond\u00f4nia"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/06\/IMG-20230612-WA0416-1024x769.jpg\" alt=\"\" class=\"wp-image-44171\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/06\/IMG-20230612-WA0416-1024x769.jpg 1024w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/06\/IMG-20230612-WA0416-300x225.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/06\/IMG-20230612-WA0416-768x576.jpg 768w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/06\/IMG-20230612-WA0416-1536x1153.jpg 1536w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/06\/IMG-20230612-WA0416-150x113.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/06\/IMG-20230612-WA0416.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Parlamentar prestigiou a solenidade que contou com posses de outras lideran\u00e7as<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>A deputada federal S\u00edlvia Cristina (PL), participou no \u00faltimo s\u00e1bado (10), da solenidade de posse do gr\u00e3o mestre estadual do Grande Oriente do Brasil (GOB), em Rond\u00f4nia, Claudenilson Alves, do gr\u00e3o mestre estadual adjunto, Celson Cabral, al\u00e9m de secret\u00e1rios e do presidente da Poderosa Assembleia Legislativa do GOB-RO, Gerson Patroc\u00ednio Santos Paes. Todos exercer\u00e3o o mandato no quadri\u00eanio 2023\/2027.<br>&#8220;Uma deputada federal tem um compromisso de representar uma sociedade como um todo, n\u00e3o apenas um segmento ou parcela da popula\u00e7\u00e3o. Conviver, dialogar e respeitar os diferentes grupos que formam essa sociedade, \u00e9 fundamental e salutar. Por isso, estive prestigiando a posse do nosso amigo querido, Claudenilson Alves como gr\u00e3o mestre estadual do GOB-RO&#8221;, destacou a parlamentar.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/06\/IMG-20230612-WA0417-1024x768.jpg\" alt=\"\" class=\"wp-image-44172\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/06\/IMG-20230612-WA0417-1024x768.jpg 1024w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/06\/IMG-20230612-WA0417-300x225.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/06\/IMG-20230612-WA0417-768x576.jpg 768w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/06\/IMG-20230612-WA0417-1536x1152.jpg 1536w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/06\/IMG-20230612-WA0417-150x113.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2023\/06\/IMG-20230612-WA0417.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><br>S\u00edlvia Cristina desejou sucesso a todos e registrou o seu reconhecimento ao trabalho da Ma\u00e7onaria em Rond\u00f4nia. &#8220;Desejo muito sucesso, foram escolhidos por serem preparados para dar continuidade ao trabalho. Quero tamb\u00e9m agradecer por ter sido agraciada com o pin de identifica\u00e7\u00e3o do Grande Oriente do Brasil Rond\u00f4nia, comenda que muito me honra, porque sou admiradora do trabalho que a Ma\u00e7onaria desenvolve em nosso Estado&#8221;. <\/p>\n\n\n\n<p>Assessoria <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A deputada federal S\u00edlvia Cristina (PL), participou no \u00faltimo s\u00e1bado (10), da solenidade de posse do gr\u00e3o mestre estadual do<\/p>\n","protected":false},"author":1,"featured_media":44171,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[303,470],"tags":[541],"class_list":["post-44170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-silvia-cristina","tag-silvia-cristina"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/44170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=44170"}],"version-history":[{"count":2,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/44170\/revisions"}],"predecessor-version":[{"id":44174,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/44170\/revisions\/44174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/44171"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=44170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=44170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=44170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}