{"id":41564,"date":"2022-11-09T13:33:32","date_gmt":"2022-11-09T17:33:32","guid":{"rendered":"https:\/\/vipfesta.com.br\/vipfesta\/?p=41564"},"modified":"2022-11-09T13:33:34","modified_gmt":"2022-11-09T17:33:34","slug":"11a-conferencia-municipal-discute-os-direitos-da-crianca-e-adolescente","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/11a-conferencia-municipal-discute-os-direitos-da-crianca-e-adolescente\/","title":{"rendered":"11\u00aa confer\u00eancia municipal discute os direitos da crian\u00e7a e adolescente"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"334\" class=\"wp-image-41566\" style=\"width: 500px;\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/11\/CONFERENCIA-CMDCA-2-1.jpg\" alt=\"\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/11\/CONFERENCIA-CMDCA-2-1.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/11\/CONFERENCIA-CMDCA-2-1-300x200.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/11\/CONFERENCIA-CMDCA-2-1-150x100.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n\n\n\n<p>O objetivo \u00e9 propor as a\u00e7\u00f5es necess\u00e1rias de repara\u00e7\u00e3o p\u00f3s-pandemia<\/p>\n\n\n\n<p>Est\u00e1 sendo realizada a 11\u00aa Confer\u00eancia Municipal dos Direitos da Crian\u00e7a e Adolescente (CMDCA), na C\u00e2mara Municipal de Ji-Paran\u00e1 (CMJP), nesta quarta-feira (9), para debater a\u00e7\u00f5es de pol\u00edticas p\u00fablicas que favore\u00e7am meninos e meninas de at\u00e9 17 anos. O evento \u00e9 organizado pela CMDCA, em parceria com a Prefeitura de Ji-Paran\u00e1, por meio da Secretaria Municipal de Assist\u00eancia Social e Fam\u00edlia (Semasf). A conven\u00e7\u00e3o segue at\u00e9 amanh\u00e3 (10).<\/p>\n\n\n\n<p>A finalidade \u00e9 discutir propostas para a 12\u00aa Confer\u00eancia Nacional dos Direitos da Crian\u00e7a e Adolescente (CNDCA) que ocorre em novembro de 2023, em Bras\u00edlia (DF), com todos os representantes municipais. Cada munic\u00edpio brasileiro realiza a conven\u00e7\u00e3o para levantar diretrizes que ir\u00e3o compor as metas do Conselho Nacional dos Direitos da Crian\u00e7a e Adolescente (Conanda). <\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"334\" class=\"wp-image-41567\" style=\"width: 500px;\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/11\/CONFERENCIA-CMDCA-4_2.jpg\" alt=\"\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/11\/CONFERENCIA-CMDCA-4_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/11\/CONFERENCIA-CMDCA-4_2-300x200.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/11\/CONFERENCIA-CMDCA-4_2-150x100.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n\n\n\n<p>O tema da 12\u00aa CNDCA ser\u00e1 a \u201cSitua\u00e7\u00e3o dos direitos humanos de crian\u00e7as e adolescentes em tempo de pandemia da Covid-19: viola\u00e7\u00f5es e vulnerabilidades, a\u00e7\u00f5es necess\u00e1rias para repara\u00e7\u00e3o e garantia de pol\u00edticas de prote\u00e7\u00e3o integral, com respeito \u00e0 diversidade\u201d.<\/p>\n\n\n\n<p>O secret\u00e1rio municipal de Administra\u00e7\u00e3o (Semad), J\u00f4natas Fran\u00e7a, representando o Prefeito Isa\u00fa Fonseca, ressaltou que a confer\u00eancia tem a finalidade de reunir representantes da sociedade civil organizada, entidades filantr\u00f3picas e poderes p\u00fablicos para discutir propostas visando fortalecer as pol\u00edticas p\u00fablicas. &nbsp;<\/p>\n\n\n\n<p>Para a presidente do CMDCA e secret\u00e1ria da Semasf, Ana Maria Santos Vizeli, durante esse per\u00edodo da pandemia da Covid-19, muitas crian\u00e7as e adolescentes foram afetados e colocados em situa\u00e7\u00f5es de vulnerabilidade. Ela refor\u00e7ou que propostas levantadas neste encontro podem ser inclu\u00eddas no plano nacional da 12\u00aa CNDCA.<\/p>\n\n\n\n<p>Segundo a representante e palestrante do Conedca, M\u00e1rcia Cristina Tesser, a partir dessas confer\u00eancias, vamos selecionar delegados e representantes das entidades para delibera\u00e7\u00e3o de pol\u00edticas p\u00fablicas que ser\u00e3o realizadas no decorrer dos pr\u00f3ximos anos. &#8220;Precisamos discutir a\u00e7\u00f5es que reparem situa\u00e7\u00f5es que se agravaram no per\u00edodo da pandemia, respeitando as diversidades do indiv\u00edduo&#8221;.<\/p>\n\n\n\n<p>Para a Defensora P\u00fablica, L\u00edvia Carvalho Cantadori Iglecias, \u00e9 um momento muito importante, pois estamos reunindo representantes para uma rede de prote\u00e7\u00e3o que al\u00e9m de garantir precisamos avan\u00e7ar nestas pol\u00edticas p\u00fablicas voltadas para crian\u00e7as e adolescentes.&nbsp; A defensora p\u00fablica concluiu que acolhidos ou institucionalizados essas meninas e meninos em situa\u00e7\u00e3o de vulnerabilidade precisam ter um desenvolvimento melhor e seus direitos<\/p>\n\n\n\n<p>A confer\u00eancia re\u00fane representantes do Conselho Estadual dos Direitos da Crian\u00e7a e Adolescente (CONEDCA\/RO), Minist\u00e9rio P\u00fablico de Rond\u00f4nia (MPRO), Tribunal de Justi\u00e7a, Defensoria P\u00fablica, 1\u00ba e 2\u00ba Conselho Tutelar e da Pol\u00edcia Militar e o adolescente Diego Kau\u00e3 da Silva, 13 anos, representando todas as crian\u00e7as e adolescente do evento.<\/p>\n\n\n\n<p>Em um momento emocionante, alunos do 4\u00ba ano do Centro Municipal de Educa\u00e7\u00e3o Infantil E Fundamental (CMEIEF) Ruth Rocha realizaram uma apresenta\u00e7\u00e3o em libras da m\u00fasica \u201cFlor e o Beija-Flor\u201d. A programa\u00e7\u00e3o da 11\u00aa Confer\u00eancia Municipal dos Direitos da Crian\u00e7a e Adolescente encerra hoje (9) \u00e0s 18h, e amanh\u00e3 (10) das 7h30 \u00e0s 15h.\u00a0<\/p>\n\n\n\n<p>Decom<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O objetivo \u00e9 propor as a\u00e7\u00f5es necess\u00e1rias de repara\u00e7\u00e3o p\u00f3s-pandemia Est\u00e1 sendo realizada a 11\u00aa Confer\u00eancia Municipal dos Direitos da<\/p>\n","protected":false},"author":1,"featured_media":41566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[283,358],"tags":[19],"class_list":["post-41564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","category-conferencia","tag-ji-parana"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/41564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=41564"}],"version-history":[{"count":2,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/41564\/revisions"}],"predecessor-version":[{"id":41568,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/41564\/revisions\/41568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/41566"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=41564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=41564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=41564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}