{"id":40474,"date":"2022-07-19T14:57:14","date_gmt":"2022-07-19T18:57:14","guid":{"rendered":"https:\/\/vipfesta.com.br\/vipfesta\/?p=40474"},"modified":"2022-07-21T21:26:03","modified_gmt":"2022-07-22T01:26:03","slug":"concluido-recapeamento-da-avenida-menezes-filho","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/concluido-recapeamento-da-avenida-menezes-filho\/","title":{"rendered":"Conclu\u00eddo recapeamento da avenida Menezes Filho"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"481\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/07\/RECAPEAMENTO-MENEZES-FILHO-2_2.jpg\" alt=\"\" class=\"wp-image-40476\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/07\/RECAPEAMENTO-MENEZES-FILHO-2_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/07\/RECAPEAMENTO-MENEZES-FILHO-2_2-300x200.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/07\/RECAPEAMENTO-MENEZES-FILHO-2_2-150x100.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><figcaption>Trecho beneficiado da via dupla era cal\u00e7ado com bloquetes<\/figcaption><\/figure>\n\n\n\n<p>Em mais uma a\u00e7\u00e3o de melhoramento de ruas pavimentadas da cidade, a Prefeitura de Ji-Paran\u00e1, por meio da Secretaria Municipal de Obras e Servi\u00e7os P\u00fablicos (Semosp), concluiu os trabalhos de recapeamento em mais de 2.800 metros de extens\u00e3o da avenida Menezes Filho. A via ainda receber\u00e1 sinaliza\u00e7\u00e3o horizontal e vertical.<\/p>\n\n\n\n<p>O trabalho de recapeamento foi feito, em pista dupla, por toda a extens\u00e3o da Menezes Filho (cerca de 1.400 metros em cada sentido), entre a avenida Marechal Rondon e rua das Pedras, nos bairros 2 de abril e Jardim dos Migrantes, no 1\u00ba distrito.  <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"481\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/07\/RECAPEAMENTO-MENEZES-FILHO-1_2.jpg\" alt=\"\" class=\"wp-image-40477\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/07\/RECAPEAMENTO-MENEZES-FILHO-1_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/07\/RECAPEAMENTO-MENEZES-FILHO-1_2-300x200.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/07\/RECAPEAMENTO-MENEZES-FILHO-1_2-150x100.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure>\n\n\n\n<p>Nos \u00faltimos dois meses, a via estava sendo preparada para receber o recape. Neste per\u00edodo, foram realizados reperfilamento, com alargamento do meio-fio em diversos pontos da via, nos dois lados da pista. Al\u00e9m dos alargamentos, a equipe da Semosp corrigiu o n\u00edvel da pista em pontos cr\u00edticos. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"406\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/07\/IMG_20210709_215336617_2.jpg\" alt=\"\" class=\"wp-image-40478\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/07\/IMG_20210709_215336617_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/07\/IMG_20210709_215336617_2-300x169.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/07\/IMG_20210709_215336617_2-150x84.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><figcaption>Big Bang Pizzaria fica localizado na Av. Menezes Filho<\/figcaption><\/figure>\n\n\n\n<p>Paralela \u00e0 avenida Monte Castelo, a Menezes Filho liga o com\u00e9rcio da Marechal Rondon com os bairros Novo Urup\u00e1 e acesso ao Novo Ji-Paran\u00e1. \u201cMelhorar a mobilidade das ruas de Ji-Paran\u00e1 e a acessibilidade, continuam sendo prioridades em nossa administra\u00e7\u00e3o\u201d, garantiu o Prefeito Isa\u00fa Fonseca.<\/p>\n\n\n\n<p>Dando sequ\u00eancia aos trabalhos de revitaliza\u00e7\u00e3o das vias urbanas, a equipe de asfaltamento da Semosp dirige suas aten\u00e7\u00f5es para realizar o recapeamento em um trecho de cerca de 100 metros da rua S\u00e3o Crist\u00f3v\u00e3o, entre Menezes Filho e Monte Castelo.<\/p>\n\n\n\n<p>Nos \u00faltimos 18 meses, a Prefeitura de Ji-Paran\u00e1 j\u00e1 levou o recapeamento a mais 50 quil\u00f4metros de ruas e avenidas da cidade. A obra \u00e9 executada com Concreto Betuminoso Usinado a Quente (CBUQ). <\/p>\n\n\n\n<p>Decom<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em mais uma a\u00e7\u00e3o de melhoramento de ruas pavimentadas da cidade, a Prefeitura de Ji-Paran\u00e1, por meio da Secretaria Municipal<\/p>\n","protected":false},"author":1,"featured_media":40476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[283,347],"tags":[601,19],"class_list":["post-40474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","category-jiparana","tag-big-bang-pizzaria","tag-ji-parana"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/40474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=40474"}],"version-history":[{"count":3,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/40474\/revisions"}],"predecessor-version":[{"id":40510,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/40474\/revisions\/40510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/40476"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=40474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=40474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=40474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}