{"id":37961,"date":"2022-03-10T16:38:33","date_gmt":"2022-03-10T20:38:33","guid":{"rendered":"https:\/\/vipfesta.com.br\/vipfesta\/?p=37961"},"modified":"2022-03-10T18:14:14","modified_gmt":"2022-03-10T22:14:14","slug":"diretoria-da-cdl-se-reune-com-a-coordenacao-da-rondonia-rural-show","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/diretoria-da-cdl-se-reune-com-a-coordenacao-da-rondonia-rural-show\/","title":{"rendered":"Diretoria da CDL se re\u00fane com a coordena\u00e7\u00e3o da Rond\u00f4nia Rural Show"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"539\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/03\/cdl-.jpg\" alt=\"\" class=\"wp-image-37970\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/03\/cdl-.jpg 720w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/03\/cdl--300x225.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/03\/cdl--150x112.jpg 150w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p>Diretoria da CDL de Ji-Paran\u00e1 se re\u00fane com a coordena\u00e7\u00e3o da Rond\u00f4nia Rural Show para conhecer o modelo estrutural da nona edi\u00e7\u00e3o da Feira de neg\u00f3cios da Rond\u00f4nia Rural Show. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"539\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/03\/Screenshot_20220310-1628102.png\" alt=\"\" class=\"wp-image-37965\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/03\/Screenshot_20220310-1628102.png 720w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/03\/Screenshot_20220310-1628102-300x225.png 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/03\/Screenshot_20220310-1628102-150x112.png 150w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p>A reuni\u00e3o foi conduzida pelo vice-presidente da CDL Elias Pereira e a apresenta\u00e7\u00e3o da estrutura da feira foi feita pela Regiane Lucas, coordenadora da RRS.<\/p>\n\n\n\n<p>A feira inicia no dia 23 e segue at\u00e9 o dia 28 de maio. A expectativa \u00e9 movimentar mais de 1 bilh\u00e3o de reais. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"539\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/03\/Screenshot_20220310-1628202.png\" alt=\"\" class=\"wp-image-37963\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/03\/Screenshot_20220310-1628202.png 720w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/03\/Screenshot_20220310-1628202-300x225.png 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/03\/Screenshot_20220310-1628202-150x112.png 150w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p>Marcaram presen\u00e7a na reuni\u00e3o os diretores da entidade Osmar Farinacio, Milton Fugiwara, Marcelo Raimundo, Robson Ant\u00f4nio, Jos\u00e9 Viana e Jeferson Miranda.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>CDL\/Ji-Paran\u00e1 <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diretoria da CDL de Ji-Paran\u00e1 se re\u00fane com a coordena\u00e7\u00e3o da Rond\u00f4nia Rural Show para conhecer o modelo estrutural da<\/p>\n","protected":false},"author":1,"featured_media":37970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[339,293,438],"tags":[113],"class_list":["post-37961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cdl","category-empresarial","category-rondonia-rural-show","tag-reuniao"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/37961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=37961"}],"version-history":[{"count":2,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/37961\/revisions"}],"predecessor-version":[{"id":37971,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/37961\/revisions\/37971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/37970"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=37961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=37961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=37961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}