{"id":36950,"date":"2022-01-25T12:34:35","date_gmt":"2022-01-25T16:34:35","guid":{"rendered":"https:\/\/vipfesta.com.br\/vipfesta\/?p=36950"},"modified":"2022-01-25T12:34:36","modified_gmt":"2022-01-25T16:34:36","slug":"prefeito-se-reune-com-gerente-do-pa-agro-da-caixa-em-ji-parana","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/prefeito-se-reune-com-gerente-do-pa-agro-da-caixa-em-ji-parana\/","title":{"rendered":"Prefeito se re\u00fane com gerente do PA Agro da Caixa em Ji-Paran\u00e1"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"508\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/01\/REUNIAO-CAIXA-1_2.jpg\" alt=\"\" class=\"wp-image-36951\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/01\/REUNIAO-CAIXA-1_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/01\/REUNIAO-CAIXA-1_2-300x211.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/01\/REUNIAO-CAIXA-1_2-150x106.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><figcaption>Encontro foi realizado na manh\u00e3 desta ter\u00e7a-feira, no Pal\u00e1cio Urup\u00e1<\/figcaption><\/figure>\n\n\n\n<p>O Prefeito de Ji-Paran\u00e1, Isa\u00fa Fonseca, se reuniu com a gerente geral do Ponto de Atendimento (PA) Agro da Caixa Econ\u00f4mica Federal em Ji-Paran\u00e1, Francielle Leandra. O encontro foi realizado na manh\u00e3 desta ter\u00e7a-feira (25), no gabinete principal do Pal\u00e1cio Urup\u00e1.<\/p>\n\n\n\n<p>O PA Agro \u00e9 uma unidade criada para atendimento exclusivo aos produtores de Ji-Paran\u00e1 e da regi\u00e3o central do estado, facilitando o acesso ao cr\u00e9dito para os pequenos e m\u00e9dios produtores rurais.<\/p>\n\n\n\n<p>\u201cViemos apresentar o PA Agro de Ji-Paran\u00e1 ao prefeito Isa\u00fa. A unidade se trata de um atendimento especializado ao produtor rural. Quando o produtor rural procura a Caixa Econ\u00f4mica, em busca de um cr\u00e9dito, acaba hesitando por conta da fila. Com o PA Agro, ele ter\u00e1 um espa\u00e7o exclusivo para atendimento\u201d, explicou Francielle.<\/p>\n\n\n\n<p>O titular da Secretaria Municipal de Agricultura e Pecu\u00e1ria (Semagri), Jesse Mendon\u00e7a Bittencourt, tamb\u00e9m participou da reuni\u00e3o e destacou a import\u00e2ncia do alinhamento entre a Administra\u00e7\u00e3o Municipal e a Caixa Econ\u00f4mica Federal. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"480\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/01\/REUNIAO-CAIXA-3_2.jpg\" alt=\"\" class=\"wp-image-36952\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/01\/REUNIAO-CAIXA-3_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/01\/REUNIAO-CAIXA-3_2-300x200.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2022\/01\/REUNIAO-CAIXA-3_2-150x100.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure>\n\n\n\n<p>\u201cA Prefeitura deve facilitar esse acesso, fazer com que os benef\u00edcios cheguem a quem realmente precisa. A Semagri tem o contato direto com os produtores do munic\u00edpio e pode intermediar o encontro entre o produtor e a Caixa\u201d, afirmou o secret\u00e1rio da Semagri.<\/p>\n\n\n\n<p>O PA Agro come\u00e7ou a atender a popula\u00e7\u00e3o em outubro de 2021. A unidade funciona dentro da ag\u00eancia da Caixa no centro de Ji-Paran\u00e1. Mas, segundo Francielle Leandra, em breve o PA Agro dever\u00e1 contar com um ponto para atendimento exclusivo aos produtores rurais.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Prefeito de Ji-Paran\u00e1, Isa\u00fa Fonseca, se reuniu com a gerente geral do Ponto de Atendimento (PA) Agro da Caixa<\/p>\n","protected":false},"author":1,"featured_media":36951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[283,347],"tags":[36],"class_list":["post-36950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","category-jiparana","tag-prefeitura"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/36950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=36950"}],"version-history":[{"count":1,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/36950\/revisions"}],"predecessor-version":[{"id":36953,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/36950\/revisions\/36953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/36951"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=36950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=36950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=36950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}