{"id":36565,"date":"2021-12-28T10:19:08","date_gmt":"2021-12-28T14:19:08","guid":{"rendered":"https:\/\/vipfesta.com.br\/vipfesta\/?p=36565"},"modified":"2021-12-28T10:19:10","modified_gmt":"2021-12-28T14:19:10","slug":"prefeitura-de-ji-parana-investiu-na-educacao-municipal-em-2021","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/prefeitura-de-ji-parana-investiu-na-educacao-municipal-em-2021\/","title":{"rendered":"Prefeitura de Ji-Paran\u00e1 investiu na Educa\u00e7\u00e3o Municipal em 2021"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"406\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/12\/AULAS-PRESENCIAIS-1.jpg\" alt=\"\" class=\"wp-image-36566\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/12\/AULAS-PRESENCIAIS-1.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/12\/AULAS-PRESENCIAIS-1-300x169.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/12\/AULAS-PRESENCIAIS-1-150x84.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><figcaption>Lavabos e totens com \u00e1lcool em gel foram instalados nas escolas<\/figcaption><\/figure>\n\n\n\n<p>A Prefeitura de Ji-Paran\u00e1 realizou um balan\u00e7o das principais a\u00e7\u00f5es desenvolvidas ao longo de 2021.&nbsp;A Secretaria Municipal de Educa\u00e7\u00e3o (Semed) retomou as aulas presenciais no m\u00eas de novembro, com as escolas passando por adequa\u00e7\u00f5es para evitar o cont\u00e1gio de Covid-19 nas unidades.<\/p>\n\n\n\n<p>\u201cTivemos um ano dif\u00edcil, em que perdemos muitos amigos para essa terr\u00edvel doen\u00e7a. Na administra\u00e7\u00e3o p\u00fablica, tamb\u00e9m foi um ano de grandes desafios, conseguir lidar com as dificuldades que essa pandemia nos imp\u00f4s\u201d, destacou o Prefeito de Ji-Paran\u00e1, Isa\u00fa Fonseca (MDB). <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"480\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/12\/ENTREGA-KITS-1.jpg\" alt=\"\" class=\"wp-image-36567\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/12\/ENTREGA-KITS-1.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/12\/ENTREGA-KITS-1-300x200.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/12\/ENTREGA-KITS-1-150x100.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure>\n\n\n\n<p>Na Educa\u00e7\u00e3o, a Prefeitura de Ji-Paran\u00e1 investiu mais de R$ 11 milh\u00f5es na compra de materiais para a reforma dos telhados das escolas da Rede Municipal de Ensino. A Semed est\u00e1 finalizando o processo de aquisi\u00e7\u00e3o de notebooks para auxiliar o trabalho dos professores, um investimento de aproximadamente R$ 2,7 milh\u00f5es.<\/p>\n\n\n\n<p>A Prefeitura investiu cerca de R$ 10 milh\u00f5es para a aquisi\u00e7\u00e3o de lousas digitais, que ser\u00e3o instaladas em todas as salas de aula do ensino fundamental da Educa\u00e7\u00e3o Municipal. No total, ser\u00e3o 181 equipamentos, que devem ser entregues at\u00e9 o fim de janeiro, com a previs\u00e3o que todos estejam instalados para o in\u00edcio do ano letivo de 2022.<\/p>\n\n\n\n<p>Durante a paralisa\u00e7\u00e3o das aulas presenciais, a Semed realizou a distribui\u00e7\u00e3o de aproximadamente 7 mil kits alimenta\u00e7\u00e3o do Programa Nacional de Alimenta\u00e7\u00e3o Escolar (PNAE), adquiridos com contrapartida da Administra\u00e7\u00e3o Municipal.<\/p>\n\n\n\n<p>Foram realizadas adequa\u00e7\u00f5es das escolas, com lavabos e totens de \u00e1lcool em gel, na entrada das unidades, para evitar a prolifera\u00e7\u00e3o da Covid. As aulas presenciais foram retomadas em 20 de setembro, inicialmente com 12 unidades e com capacidade de alunos reduzida para 30%. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"406\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/12\/ESCOLA-MUNICIPAL-1.jpg\" alt=\"\" class=\"wp-image-36568\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/12\/ESCOLA-MUNICIPAL-1.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/12\/ESCOLA-MUNICIPAL-1-300x169.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/12\/ESCOLA-MUNICIPAL-1-150x84.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure>\n\n\n\n<p>O ano letivo na Rede Municipal se encerrou na \u00faltima ter\u00e7a-feira, dia 21 de dezembro, quando 50% dos estudantes j\u00e1 estavam de volta \u00e0s salas de aula, de maneira escalonada em 15 unidades municipais e duas escolas conveniadas. As demais escolas seguiram com 100% dos alunos com aulas remotas.<\/p>\n\n\n\n<p>A grande not\u00edcia para os educadores veio em outubro, no m\u00eas dos professores, com a implanta\u00e7\u00e3o do benef\u00edcio de progress\u00e3o funcional (bi\u00eanio), que h\u00e1 muitos anos era almejado pelos servidores e que passou a ser pago j\u00e1 na folha daquele m\u00eas.<\/p>\n\n\n\n<p>\u201cAinda em 2021, o Prefeito Isa\u00fa Fonseca elaborou uma lei, que foi aprovada pela C\u00e2mara Municipal de Ji-Paran\u00e1 [CMJP], que facilita o pagamento do bi\u00eanio retroativo \u00e0 implanta\u00e7\u00e3o do benef\u00edcio em folha, al\u00e9m do 14\u00ba sal\u00e1rio dos servidores da Educa\u00e7\u00e3o\u201d, destacou o titular da Semed, Jeferson Barbosa. <\/p>\n\n\n\n<p>Assessoria <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Ji-Paran\u00e1 realizou um balan\u00e7o das principais a\u00e7\u00f5es desenvolvidas ao longo de 2021.&nbsp;A Secretaria Municipal de Educa\u00e7\u00e3o (Semed)<\/p>\n","protected":false},"author":1,"featured_media":36566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[283,373,347],"tags":[36],"class_list":["post-36565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","category-educacao","category-jiparana","tag-prefeitura"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/36565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=36565"}],"version-history":[{"count":1,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/36565\/revisions"}],"predecessor-version":[{"id":36569,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/36565\/revisions\/36569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/36566"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=36565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=36565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=36565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}