{"id":34360,"date":"2021-10-08T14:49:39","date_gmt":"2021-10-08T18:49:39","guid":{"rendered":"https:\/\/vipfesta.com.br\/vipfesta\/?p=34360"},"modified":"2021-10-08T14:49:42","modified_gmt":"2021-10-08T18:49:42","slug":"aplicativo-geracao-emprego-e-lancado-em-ji-parana","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/aplicativo-geracao-emprego-e-lancado-em-ji-parana\/","title":{"rendered":"Aplicativo Gera\u00e7\u00e3o Emprego \u00e9 lan\u00e7ado em Ji-Paran\u00e1"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"457\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-7_2.jpg\" alt=\"\" class=\"wp-image-34361\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-7_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-7_2-300x190.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-7_2-150x95.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure>\n\n\n\n<p>Na noite desta quinta-feira (7), foi realizado o lan\u00e7amento do aplicativo Gera\u00e7\u00e3o Emprego, na C\u00e2mara Municipal de Ji-Paran\u00e1 (CMJP). O app,&nbsp;que facilita a busca por uma vaga de emprego com cadastro de curr\u00edculo, foi lan\u00e7ado em uma parceria entre o Governo do Estado e a Prefeitura de Ji-Paran\u00e1, por meio da Secretaria Municipal de Desenvolvimento e Assuntos Estrat\u00e9gicos (Semdae).<\/p>\n\n\n\n<p>O lan\u00e7amento do app Gera\u00e7\u00e3o Emprego faz parte da programa\u00e7\u00e3o da 1\u00aa Semana da Juventude Jipa, realizada com o apoio da Superintend\u00eancia da Juventude, Cultura, Esportes e Lazer (Sejucel), que come\u00e7ou na segunda-feira (4) e se encerra neste s\u00e1bado (9),&nbsp;no Gin\u00e1sio Poliesportivo Gerivaldo Jos\u00e9 de Souza (Gerivald\u00e3o), com competi\u00e7\u00f5es esportivas, das 14h \u00e0s 22h, e com o Show de Talentos Jipa, marcado para \u00e0s 19h.<\/p>\n\n\n\n<p>O Vice-prefeito de Ji-Paran\u00e1, Joaquim Teixeira (MDB), representando o Prefeito Isa\u00fa Fonseca, participou de uma reuni\u00e3o, nesta sexta-feira (8), com representantes da Superintend\u00eancia Estadual de Desenvolvimento Econ\u00f4mico e Infraestrutura (Sedi) e do Sistema Nacional de Emprego de Rond\u00f4nia (Sine-RO), para alinhar detalhes da parceria entre o Munic\u00edpio e o Estado para gera\u00e7\u00e3o de empregos na regi\u00e3o.<\/p>\n\n\n\n<p>\u201cTratamos sobre a gera\u00e7\u00e3o de novas vagas de emprego e do trabalho que \u00e9 desenvolvido pelo Sine em Ji-Paran\u00e1, com total apoio da Administra\u00e7\u00e3o Municipal. Foi uma reuni\u00e3o muito produtiva e quem tem a ganhar \u00e9 a popula\u00e7\u00e3o do nosso munic\u00edpio\u201d, ressaltou o Vice-prefeito, Joaquim Teixeira. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"488\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-2_2.jpg\" alt=\"\" class=\"wp-image-34362\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-2_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-2_2-300x203.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-2_2-150x102.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure>\n\n\n\n<p>No encontro, foi tratado sobre o projeto para cria\u00e7\u00e3o de uma nova sala de atendimento do Sine em Ji-Paran\u00e1. Atualmente, o \u00f3rg\u00e3o funciona na Central de Atendimento Tudo Aqui, no Antigo Shopping Cidad\u00e3o, no segundo distrito.<\/p>\n\n\n\n<p>\u201cN\u00f3s tratamos da parceria, para promover a amplia\u00e7\u00e3o da Rede Sine em Ji-Paran\u00e1, expandindo o servi\u00e7o prestado. Hoje atendemos no segundo distrito, mas temos a inten\u00e7\u00e3o, a pedido do Munic\u00edpio, de trazer o atendimento tamb\u00e9m para o primeiro distrito de Ji-Paran\u00e1\u201d, informou Teresa Cristina Aranha de Brito, coordenadora estadual do Sine-RO.<\/p>\n\n\n\n<p>O aplicativo j\u00e1 est\u00e1 dispon\u00edvel para download na Google Play e na App Store, com vers\u00f5es para o empregador e tamb\u00e9m para quem est\u00e1 procurando uma nova oportunidade de emprego. Basta procurar por \u201cGera\u00e7\u00e3o Emprego\u201d na loja de Apps do celular e baixar a vers\u00e3o desejada.<\/p>\n\n\n\n<p>\u201cO aplicativo gera um curr\u00edculo, conforme as informa\u00e7\u00f5es que o candidato \u00e0 vaga informar. Com esta ferramenta, vamos diminuir muito os custos do empregador e da pessoa que procura um emprego. A ferramenta dinamiza e estreita o la\u00e7o entre quem est\u00e1 precisando de trabalho e quem est\u00e1 ofertando uma vaga de emprego. O aplicativo vai agregar muito para a popula\u00e7\u00e3o de Ji-Paran\u00e1, em especial para os jovens do munic\u00edpio\u201d, destacou Maria Penha Nardi, titular da Semdae.<\/p>\n\n\n\n<p>O titular da Secretaria Municipal de Planejamento (Semplan), Rui Vieira de Souza, destacou a import\u00e2ncia da parceria entre a Prefeitura de Ji-Paran\u00e1 e o Governo do Estado, que se unem para combater o desemprego, em especial para o p\u00fablico mais jovem que est\u00e1 em busca da primeira oportunidade no mercado de trabalho.<\/p>\n\n\n\n<p>\u201cO Governo de Rond\u00f4nia, por meio de Sedi, veio para Ji-Paran\u00e1 para somar neste grande desafio que \u00e9 a gera\u00e7\u00e3o de empregos. \u00c9 mais uma a\u00e7\u00e3o dessa grande parceria que temos entre a Prefeitura e o Estado\u201d, afirmou Rui Vieira.<\/p>\n\n\n\n<p>O coordenador t\u00e9cnico da Sedi,\u00a0Avenilson Gomes da Trindade, tamb\u00e9m participou da reuni\u00e3o realizada no Pal\u00e1cio Urup\u00e1, representando o superintendente da Sedi, S\u00e9rgio Gon\u00e7alves da Silva.<\/p>\n\n\n\n<p>Assessoria <\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"481\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/RENIAO-VICE-VINICIUS-3_2.jpg\" alt=\"\" data-id=\"34363\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/RENIAO-VICE-VINICIUS-3_2.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34363\" class=\"wp-image-34363\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/RENIAO-VICE-VINICIUS-3_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/RENIAO-VICE-VINICIUS-3_2-300x200.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/RENIAO-VICE-VINICIUS-3_2-150x100.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"481\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/RENIAO-VICE-VINICIUS-1_2.jpg\" alt=\"\" data-id=\"34369\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/RENIAO-VICE-VINICIUS-1_2.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34369\" class=\"wp-image-34369\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/RENIAO-VICE-VINICIUS-1_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/RENIAO-VICE-VINICIUS-1_2-300x200.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/RENIAO-VICE-VINICIUS-1_2-150x100.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"481\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-4_2.jpg\" alt=\"\" data-id=\"34366\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-4_2.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34366\" class=\"wp-image-34366\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-4_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-4_2-300x200.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-4_2-150x100.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"481\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-3_2.jpg\" alt=\"\" data-id=\"34365\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-3_2.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34365\" class=\"wp-image-34365\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-3_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-3_2-300x200.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-3_2-150x100.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"450\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-6_2.jpg\" alt=\"\" data-id=\"34368\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-6_2.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34368\" class=\"wp-image-34368\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-6_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-6_2-300x187.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-6_2-150x94.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"534\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-5_2.jpg\" alt=\"\" data-id=\"34367\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-5_2.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34367\" class=\"wp-image-34367\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-5_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-5_2-300x222.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/10\/APP-LANCAMENTO-JOTA-5_2-150x111.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Na noite desta quinta-feira (7), foi realizado o lan\u00e7amento do aplicativo Gera\u00e7\u00e3o Emprego, na C\u00e2mara Municipal de Ji-Paran\u00e1 (CMJP). O<\/p>\n","protected":false},"author":1,"featured_media":34361,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[283,347],"tags":[669],"class_list":["post-34360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","category-jiparana","tag-emprego"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/34360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=34360"}],"version-history":[{"count":1,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/34360\/revisions"}],"predecessor-version":[{"id":34370,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/34360\/revisions\/34370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/34361"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=34360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=34360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=34360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}