{"id":34096,"date":"2021-09-27T23:25:39","date_gmt":"2021-09-28T03:25:39","guid":{"rendered":"https:\/\/vipfesta.com.br\/vipfesta\/?p=34096"},"modified":"2021-09-28T00:16:33","modified_gmt":"2021-09-28T04:16:33","slug":"1-encontro-clube-mesa-posta-rondonia","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/1-encontro-clube-mesa-posta-rondonia\/","title":{"rendered":"1\u00b0 Encontro Clube Mesa Posta Rond\u00f4nia"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"406\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163606145_2.jpg\" alt=\"\" class=\"wp-image-34110\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163606145_2.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163606145_2-300x169.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163606145_2-150x84.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure>\n\n\n\n<p>Meseiras de v\u00e1rios munic\u00edpios do Estado se reuniram na tarde do s\u00e1bado (25) para o 1\u00b0 Encontro Clube Mesa Posta Rond\u00f4nia. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"1\u00b0 Encontro Clube Mesa Posta Rond\u00f4nia\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/b96TjpR_3qE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption>Namir &#8211; Clube Mesa Posta Rond\u00f4nia<\/figcaption><\/figure>\n\n\n\n<p>O evento aconteceu no Hotel Maximus Sottile, e foi super divertido onde as meseiras puderam se conhecer de perto e compartilhar inspira\u00e7\u00f5es, suas mesas e um pouquinho da sua vida no grupo.<\/p>\n\n\n\n<p>Ap\u00f3s as palestras, as mulheres apaixonadas por mesa posta, foram agraciadas com um delicioso coquetel e sorteio de brindes, confira as fotos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong><a href=\"https:\/\/photos.app.goo.gl\/hqRofwgw1L8T7q8r8\" target=\"_blank\" rel=\"noreferrer noopener\">VEJA AQUI TODAS AS FOTOS<\/a><\/strong><\/h4>\n\n\n\n<p>\u2b06\ufe0f\ud83e\udd33<\/p>\n\n\n\n<p>Siga: <a href=\"http:\/\/instagram.com\/vipfestaoficial\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>instagram.com\/vipfestaoficial<\/strong><\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162600761_2-576x1024.jpg\" alt=\"\" data-id=\"34108\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162600761_2.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34108\" class=\"wp-image-34108\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162600761_2-576x1024.jpg 576w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162600761_2-169x300.jpg 169w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162600761_2-150x267.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162600761_2.jpg 722w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162738678-576x1024.jpg\" alt=\"\" data-id=\"34105\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162738678.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34105\" class=\"wp-image-34105\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162738678-576x1024.jpg 576w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162738678-169x300.jpg 169w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162738678-150x267.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162738678.jpg 722w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162850638-576x1024.jpg\" alt=\"\" data-id=\"34102\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162850638.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34102\" class=\"wp-image-34102\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162850638-576x1024.jpg 576w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162850638-169x300.jpg 169w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162850638-150x267.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162850638.jpg 722w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162833967-576x1024.jpg\" alt=\"\" data-id=\"34103\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162833967.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34103\" class=\"wp-image-34103\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162833967-576x1024.jpg 576w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162833967-169x300.jpg 169w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162833967-150x267.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162833967.jpg 722w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162809268-576x1024.jpg\" alt=\"\" data-id=\"34104\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162809268.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34104\" class=\"wp-image-34104\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162809268-576x1024.jpg 576w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162809268-169x300.jpg 169w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162809268-150x267.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162809268.jpg 722w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162719100-576x1024.jpg\" alt=\"\" data-id=\"34106\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162719100.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34106\" class=\"wp-image-34106\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162719100-576x1024.jpg 576w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162719100-169x300.jpg 169w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162719100-150x267.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162719100.jpg 722w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162703474-576x1024.jpg\" alt=\"\" data-id=\"34107\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162703474.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34107\" class=\"wp-image-34107\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162703474-576x1024.jpg 576w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162703474-169x300.jpg 169w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162703474-150x267.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162703474.jpg 722w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162959229_2-576x1024.jpg\" alt=\"\" data-id=\"34099\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162959229_2.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34099\" class=\"wp-image-34099\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162959229_2-576x1024.jpg 576w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162959229_2-169x300.jpg 169w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162959229_2-150x267.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162959229_2.jpg 722w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162944285_2-576x1024.jpg\" alt=\"\" data-id=\"34100\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162944285_2.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34100\" class=\"wp-image-34100\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162944285_2-576x1024.jpg 576w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162944285_2-169x300.jpg 169w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162944285_2-150x267.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162944285_2.jpg 722w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163016449_2-576x1024.jpg\" alt=\"\" data-id=\"34098\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163016449_2.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34098\" class=\"wp-image-34098\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163016449_2-576x1024.jpg 576w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163016449_2-169x300.jpg 169w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163016449_2-150x267.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163016449_2.jpg 722w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162926680_2-576x1024.jpg\" alt=\"\" data-id=\"34101\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162926680_2.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34101\" class=\"wp-image-34101\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162926680_2-576x1024.jpg 576w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162926680_2-169x300.jpg 169w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162926680_2-150x267.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162926680_2.jpg 722w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163621261_2-576x1024.jpg\" alt=\"\" data-id=\"34097\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163621261_2.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34097\" class=\"wp-image-34097\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163621261_2-576x1024.jpg 576w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163621261_2-169x300.jpg 169w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163621261_2-150x267.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_163621261_2.jpg 722w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"406\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162512607.jpg\" alt=\"\" data-id=\"34109\" data-full-url=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162512607.jpg\" data-link=\"https:\/\/vipfesta.com.br\/vipfesta\/?attachment_id=34109\" class=\"wp-image-34109\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162512607.jpg 721w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162512607-300x169.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/09\/IMG_20210925_162512607-150x84.jpg 150w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Meseiras de v\u00e1rios munic\u00edpios do Estado se reuniram na tarde do s\u00e1bado (25) para o 1\u00b0 Encontro Clube Mesa Posta<\/p>\n","protected":false},"author":1,"featured_media":34110,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[295],"tags":[],"class_list":["post-34096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/34096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=34096"}],"version-history":[{"count":5,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/34096\/revisions"}],"predecessor-version":[{"id":34118,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/34096\/revisions\/34118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/34110"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=34096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=34096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=34096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}