{"id":30513,"date":"2021-03-02T19:59:31","date_gmt":"2021-03-02T23:59:31","guid":{"rendered":"https:\/\/vipfesta.com.br\/vipfesta\/?p=30513"},"modified":"2021-03-02T20:01:29","modified_gmt":"2021-03-03T00:01:29","slug":"obras-de-escoamentos-do-morar-melhor-recebe-r-15-milhao-de-recursos-de-silvia-cristina-e-acir","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/obras-de-escoamentos-do-morar-melhor-recebe-r-15-milhao-de-recursos-de-silvia-cristina-e-acir\/","title":{"rendered":"Obras de escoamentos do Morar Melhor recebe R$ 1,5 milh\u00e3o de recursos de S\u00edlvia Cristina e Acir"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>A deputada federal S\u00edlvia Cristina (PDT), em sess\u00e3o na C\u00e2mara Municipal de Ji-Paran\u00e1 nesta \u00faltima ter\u00e7a-feira (02), informou que ela, juntamente com o senador Acir Gurgacz (PDT), est\u00e3o garantindo R$ 1,5 milh\u00e3o para obras de escoamentos dos dejetos do residencial Morar Melhor. \u201cA falta do escoamento dos dejetos era o maior empecilho para que esta obra ainda n\u00e3o tenha sido entregue aos moradores\u201d, informou a deputada.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"787\" height=\"854\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-02-at-15.03.02-1.jpeg\" alt=\"\" class=\"wp-image-30514\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-02-at-15.03.02-1.jpeg 787w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-02-at-15.03.02-1-276x300.jpeg 276w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-02-at-15.03.02-1-768x833.jpeg 768w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-02-at-15.03.02-1-150x163.jpeg 150w\" sizes=\"auto, (max-width: 787px) 100vw, 787px\" \/><figcaption>A deputada juntamente com o senador Acir, garantiram R$ 1,5 milh\u00e3o para as obras de escoamentos dos dejetos do residencial Morar Melhor<\/figcaption><\/figure>\n\n\n\n<p>Na semana passada, S\u00edlvia Cristina esteve novamente em reuni\u00e3o com o Secret\u00e1rio Nacional de Habita\u00e7\u00e3o do Minist\u00e9rio do Desenvolvimento Regional, Alfredo dos Santos, que garantiu que, juntamente com o Governo do Estado, ir\u00e3o finalizar as obras que faltam menos de 10% para serem entregues. \u201cO projeto j\u00e1 est\u00e1 ponto na prefeitura e com a libera\u00e7\u00e3o deste or\u00e7amento federal a gente encaminha um recurso fundo a fundo para que a prefeitura possa executar a obra para que essas casas sejam entregues o quanto antes a essas quase 1.500 fam\u00edlias que esperam ansiosamente por este dia\u201d, disse a deputada.&nbsp;<\/p>\n\n\n\n<p>Assessoria <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A deputada federal S\u00edlvia Cristina (PDT), em sess\u00e3o na C\u00e2mara Municipal de Ji-Paran\u00e1 nesta \u00faltima ter\u00e7a-feira (02), informou que ela,<\/p>\n","protected":false},"author":1,"featured_media":30515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[303],"tags":[1101,541],"class_list":["post-30513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-residencial","tag-silvia-cristina"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/30513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=30513"}],"version-history":[{"count":2,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/30513\/revisions"}],"predecessor-version":[{"id":30517,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/30513\/revisions\/30517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/30515"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=30513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=30513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=30513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}