{"id":299,"date":"2019-08-13T05:07:00","date_gmt":"2019-08-13T08:07:00","guid":{"rendered":"http:\/\/vipfesta.com.br\/vipfesta\/?p=299"},"modified":"2020-01-07T08:32:40","modified_gmt":"2020-01-07T11:32:40","slug":"cavalgada-da-15-expo-show-norte-2019","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/cavalgada-da-15-expo-show-norte-2019\/","title":{"rendered":"Cavalgada da 15\u00aa Expo Show Norte 2019"},"content":{"rendered":"<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<a href=\"https:\/\/1.bp.blogspot.com\/-JVw7KaIeEO8\/XVJD5GDFdYI\/AAAAAAAGy9s\/P_2wVpkADag8C-gH9Noe2_Uopnf-xo5-gCKgBGAs\/s1600\/vipfesta_DSC06097.JPG\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"1067\" data-original-width=\"1600\" height=\"213\" src=\"http:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2019\/08\/vipfesta_DSC06097.jpg\" width=\"320\" \/><\/a><\/div>\n<p>\nCavalgada da Expo Show Norte 2019 realizada no s\u00e1bado (10\/08) em Ouro Preto do Oeste, o percurso foi o mesmo do ano anterior com a concentra\u00e7\u00e3o na Av. Daniel Comboni, depois seguiu por v\u00e1rias avenidas at\u00e9 a chegada no Parque de Exposi\u00e7\u00f5es onde aconteceu um show musical dan\u00e7ante.<\/p>\n<p>A festa country reuniu dezenas de cavaleiros e amazonas de v\u00e1rios munic\u00edpios de Rond\u00f4nia, nas avenidas centenas de pessoas prestigiaram a bel\u00edssima cavalgada de abertura da exposi\u00e7\u00e3o. O site VipFesta registrou os melhores momentos, confira as fotos:<\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<a href=\"https:\/\/1.bp.blogspot.com\/-1Mi3Y1TLtHw\/XVJFOnIUw2I\/AAAAAAAGy98\/n5NBCS9jdlceCC5T39pBdnZrLj3lKV1XQCKgBGAs\/s1600\/vipfesta_DSC06093.JPG\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"1067\" data-original-width=\"1600\" height=\"133\" src=\"http:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2019\/08\/vipfesta_DSC06093.jpg\" width=\"200\" \/><\/a>&nbsp;<a href=\"https:\/\/1.bp.blogspot.com\/-mFNqmNmUsMM\/XVJEr2f1qXI\/AAAAAAAGy90\/JXXE7H04CYY0KrsFVXLtonSgEZ5r6zwjQCKgBGAs\/s1600\/vipfesta_DSC06024.JPG\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"1192\" data-original-width=\"1600\" height=\"133\" src=\"http:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2019\/08\/vipfesta_DSC06024.jpg\" width=\"200\" \/><\/a><\/div>\n<p>\nA 15\u00aa edi\u00e7\u00e3o da&nbsp; Feira Agropecu\u00e1ria Expo Show Norte, tem in\u00edcio na quarta-feira (14) e segue at\u00e9 no domingo (18). O cantor Eduardo Costa agita a galera na sexta-feira (16) e no s\u00e1bado (17) \u00e9 a vez de Bruno &amp; Barreto.<\/p>\n<div style=\"text-align: center;\">\n<a href=\"https:\/\/photos.app.goo.gl\/nv6VVt9JKSeh9A7H9\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" border=\"0\" hspace=\"2\" src=\"https:\/\/goo.gl\/Cpf37p\" \/><\/a><\/p>\n<div style=\"text-align: center;\">\n<iframe loading=\"lazy\" frameborder=\"0\" height=\"3750\" marginheight=\"0\" marginwidth=\"0\" scrolling=\"yes\" src=\"https:\/\/embedsocial.com\/facebook_album\/album_photos\/2618915271460448\/\" style=\"text-align: center;\" width=\"100%\"><\/iframe><\/div>\n<div style=\"text-align: center;\">\n<img decoding=\"async\" alt=\"VipFesta, o site mais visto de Rond\u00f4nia \u00e9 sim a melhor m\u00eddia com os melhores anunciantes\" src=\"https:\/\/goo.gl\/raaeF8\" \/>\n<\/div>\n<p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cavalgada da Expo Show Norte 2019 realizada no s\u00e1bado (10\/08) em Ouro Preto do Oeste, o percurso foi o mesmo<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[14,54,92,90],"class_list":["post-299","post","type-post","status-publish","format-standard","hentry","category-news","tag-agropecuaria","tag-cavalgadas","tag-expo-show-norte","tag-exposicao"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=299"}],"version-history":[{"count":1,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/299\/revisions"}],"predecessor-version":[{"id":22676,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/299\/revisions\/22676"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}