{"id":2964,"date":"2016-02-01T15:36:00","date_gmt":"2016-02-01T17:36:00","guid":{"rendered":"http:\/\/vipfesta.com.br\/vipfesta\/?p=2964"},"modified":"2020-01-07T08:21:26","modified_gmt":"2020-01-07T11:21:26","slug":"governador-mostra-potencial-de-rondonia","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/governador-mostra-potencial-de-rondonia\/","title":{"rendered":"Governador mostra potencial de Rond\u00f4nia durante Show Rural, no Paran\u00e1"},"content":{"rendered":"<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<a href=\"http:\/\/data.portal.sistemas.ro.gov.br\/2016\/01\/Comitiva_001-Bruno-Corsino.jpg\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" src=\"http:\/\/data.portal.sistemas.ro.gov.br\/2016\/01\/Comitiva_001-Bruno-Corsino.jpg\" height=\"245\" width=\"400\" \/><\/a><\/div>\n<p>\nO potencial produtivo e as perspectivas para investimentos em Rond\u00f4nia ser\u00e3o mostrados a visitantes e expositores do Show Rural Coopavel, em Cascavel (PR), na pr\u00f3xima segunda-feira (1), pelo governador Conf\u00facio Moura. Ele foi convidado para ministrar palestra no evento considerado o maior do agroneg\u00f3cio da Am\u00e9rica Latina, que est\u00e1 na 28\u00aa edi\u00e7\u00e3o.<\/p>\n<p>Na feira, que atraiu 230 mil visitantes brasileiros e do exterior em 2015, o governador de Rond\u00f4nia destacar\u00e1, entre outros itens, a localiza\u00e7\u00e3o geogr\u00e1fica do estado. Ele dir\u00e1 que Rond\u00f4nia oferece acesso a pa\u00edses vizinhos, como Peru, Bol\u00edvia, Equador, Col\u00f4mbia, Venezuela e Chile, configurando-se como promissor polo regional de log\u00edstica e com\u00e9rcio exterior.<\/p>\n<p>A for\u00e7a do agroneg\u00f3cio no estado tamb\u00e9m ser\u00e1 apresentada em n\u00fameros que ser\u00e3o sustentados pelas iniciativas que garantem a sustentabilidade.<\/p>\n<p>Conf\u00facio, que estar\u00e1 acompanhado do secret\u00e1rio da Agricultura, Evandro Padovani, vai discorrer ainda sobre o apoio que o estado oferece \u00e0s lavouras do caf\u00e9, cacau, mandioca, soja, feij\u00e3o e milho; e dar\u00e1 \u00eanfase ao fato de que Rond\u00f4nia \u00e9 respons\u00e1vel por 20% de toda a carne bovina exportada pelo Pa\u00eds.<\/p>\n<p>A import\u00e2ncia de Rond\u00f4nia para o Show Rural Coopavel tamb\u00e9m \u00e9 refor\u00e7ada pelos resultados positivos da Feira Rond\u00f4nia Rural Show, que teve quatro edi\u00e7\u00f5es e reuniu, no ano passado, 53 mil visitantes e 340 expositores, tornando-se um exemplo de evolu\u00e7\u00e3o no agroneg\u00f3cio.<\/p>\n<p><span style=\"font-size: x-small;\">Fonte<\/span><br \/>\n<span style=\"font-size: x-small;\">Texto: Nonato Cruz<\/span><br \/>\n<span style=\"font-size: x-small;\">Fotos: Bruno Corsino<\/span><br \/>\n<span style=\"font-size: x-small;\">Secom &#8211; Governo de Rond\u00f4nia<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O potencial produtivo e as perspectivas para investimentos em Rond\u00f4nia ser\u00e3o mostrados a visitantes e expositores do Show Rural Coopavel,<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[14],"class_list":["post-2964","post","type-post","status-publish","format-standard","hentry","category-news","tag-agropecuaria"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/2964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=2964"}],"version-history":[{"count":1,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/2964\/revisions"}],"predecessor-version":[{"id":12870,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/2964\/revisions\/12870"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=2964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=2964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=2964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}