{"id":2956,"date":"2016-02-05T01:11:00","date_gmt":"2016-02-05T03:11:00","guid":{"rendered":"http:\/\/vipfesta.com.br\/vipfesta\/?p=2956"},"modified":"2020-01-07T08:21:27","modified_gmt":"2020-01-07T11:21:27","slug":"tocha-olimpica-passara-por-porto-velho","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/tocha-olimpica-passara-por-porto-velho\/","title":{"rendered":"Tocha Ol\u00edmpica passar\u00e1 por Porto Velho dia 22 de junho"},"content":{"rendered":"<div style=\"text-align: center;\">\n<img loading=\"lazy\" decoding=\"async\" alt=\"Reuni\u00e3o sobre o revezamento da Tocha Ol\u00edmpica foi realizada no audit\u00f3rio da governadoria\" height=\"382\" src=\"http:\/\/data.portal.sistemas.ro.gov.br\/2016\/02\/Reuni%C3%A3o-sobre-Revezamento-da-Tocha-Ol%C3%ADmpica_03.02.16_Foto_Daiane-Mendon%C3%A7a-20-870x521.jpg\" width=\"640\" \/><\/div>\n<p>\nA Tocha Ol\u00edmpica, s\u00edmbolo maior da abertura dos Jogos Ol\u00edmpicos que ser\u00e3o realizados no Rio de Janeiro, a partir de agosto, passar\u00e1 por Rond\u00f4nia no dia 22 de junho. A data foi anunciada na tarde desta quarta-feira (3) pelo ministro do Esporte, George Hilton, que tamb\u00e9m anunciou investimentos para Porto Velho durante evento no audit\u00f3rio do pr\u00e9dio Paca\u00e1s Novos, Pal\u00e1cio Rio Madeira, sede do governo de Rond\u00f4nia, em Porto Velho.<\/p>\n<p>Rond\u00f4nia foi o 20\u00ba estado visitado pelo ministro, recebido com sua comitiva pelo governador Conf\u00facio Moura e prefeito em exerc\u00edcio, Dalton Di Franco, para iniciar reuni\u00f5es t\u00e9cnicas de trabalho com o objetivo de preparar o evento \u201cRevezamento da Tocha Ol\u00edmpica\u201d. George Hilton esteve na ter\u00e7a-feira (2) em Manaus (AM) e Boa Vista (RR) para a mesma atividade.<\/p>\n<p>\u201cO revezamento da tocha, al\u00e9m de proporcionar que os jogos ol\u00edmpicos e paraol\u00edmpicos possam estar em todo o Pa\u00eds, tem levado o Minist\u00e9rio do Esporte e afins para conhecer os estados. Essas reuni\u00f5es n\u00e3o s\u00e3o apenas um momento de unidade entre as inst\u00e2ncias de governo. Elas t\u00eam nos permitido conhecer os desafios, e de m\u00e3os dadas com o governador Conf\u00facio Moura e o prefeito em exerc\u00edcio vamos propor uma parceria nos v\u00e1rios n\u00edveis de governo para massificar o esporte. Podem ter certeza que Rond\u00f4nia est\u00e1 no nosso radar. \u00c9 um estado novo e precisa investir agora para que as pr\u00f3ximas gera\u00e7\u00f5es tenham acesso \u00e0 pratica esportiva, \u00e0s atividades f\u00edsicas. Estou feliz de estar aqui\u201d, disse o ministro George Hilton.<\/p>\n<p>Segundo ele, Rond\u00f4nia ser\u00e1 muito beneficiado com a passagem da Tocha Ol\u00edmpica. O governo Federal ir\u00e1 investir na constru\u00e7\u00e3o de um Centro de Inicia\u00e7\u00e3o Esportiva, no valor de R$ 3,7 milh\u00f5es, e em an\u00e1lise est\u00e1 a constru\u00e7\u00e3o de uma pista de atletismo, que inclui um campo de futebol, no campus da Universidade Federal de Rond\u00f4nia (Unir) na Capital, or\u00e7ada em R$ 8 milh\u00f5es.<\/p>\n<p>\u201cO Centro permitir\u00e1 que 20 modalidades possam ser iniciadas pelas nossas crian\u00e7as, sendo 13 ol\u00edmpicas, seis paraol\u00edmpicas e uma n\u00e3o ol\u00edmpica\u201d, detalhou.<\/p>\n<p>George Hilton disse tamb\u00e9m que o Minist\u00e9rio do Esporte prepara uma esp\u00e9cie de LDB [Lei de Diretrizes e Bases], que vai resgatar a obrigatoriedade da educa\u00e7\u00e3o f\u00edsica nas escolas e a pr\u00e1tica do esporte. \u201cQueremos estabelecer diretrizes e definir obriga\u00e7\u00f5es para cada um dos poderes, imprimir uma cultura de que o Brasil s\u00f3 tem a ganhar com a atividade f\u00edsica. O sedentarismo em nosso Pa\u00eds chegou a 45,9%, mais de 70 milh\u00f5es de pessoas paradas, sedent\u00e1rias. Se n\u00e3o combatermos isso, no futuro a conta n\u00e3o fecha. Temos de estimular o potencial para a pr\u00e1tica esportiva\u201d, afirmou.<\/p>\n<p>O subchefe de Assuntos Federativos da Presid\u00eancia da Rep\u00fablica, Olmo Xavier; e o diretor do Comit\u00ea Executivo Organizador dos Jogos Ol\u00edmpicos 2016, Marco Aur\u00e9lio Costa, tamb\u00e9m participaram da reuni\u00e3o. Na ocasi\u00e3o, o atleta paraol\u00edmpico rondoniense Rog\u00e9rio Costa Lima, premiado maratonista e campe\u00e3o brasileiro no triatlo, disse que Rond\u00f4nia tem atletas de alto n\u00edvel, tem potencial, \u201ce isso engrandece o estado\u201d.<\/p>\n<p>Em Porto Velho, a Tocha Ol\u00edmpica ficar\u00e1 durante todo o dia com o apoio da Coca-Cola, Banco Bradesco e Nissan, patrocinadores citados pelo ministro. Haver\u00e1 pontos festivos ao longo dos 37 quil\u00f4metros de trajeto da tocha pela cidade, com shows de artistas locais, entre outras atividades preparadas pelas tr\u00eas empresas.<\/p>\n<p>Segundo o coordenador de Esporte da Superintend\u00eancia Estadual da Juventude, Esporte, Cultura e Lazer (Sujucel), Edvaldo Ara\u00fajo, a Tocha Ol\u00edmpica ser\u00e1 levada ao longo do trajeto por 161 pessoas escolhidas pela prefeitura, governo do estado e patrocinadores. Ara\u00fajo participou com t\u00e9cnicos do governo Federal, da prefeitura e das Secretarias de Estado da Educa\u00e7\u00e3o (Seduc), Seguran\u00e7a P\u00fablica (Sesdec) e Superintend\u00eancia de Turismo (Setur), entre outras, de reuni\u00e3o t\u00e9cnica para definir as atribui\u00e7\u00f5es de cada \u00f3rg\u00e3o nas \u00e1reas de seguran\u00e7a e defesa, turismo, cultura e mobilidade, a fim de preparar o munic\u00edpio de Porto Velho para o evento Revezamento da Tocha Ol\u00edmpica.<\/p>\n<p>SHOW DE BOLA<\/p>\n<p>O governador Conf\u00facio Moura disse que as Olimp\u00edadas 2016 no Brasil v\u00eam em boa hora, em um momento especial, para irradiarmos para o mundo o que \u00e9 o Brasil, levando uma mensagem positiva sobre o Pa\u00eds, se contrapondo \u00e0 situa\u00e7\u00e3o econ\u00f4mica e pol\u00edtica atual.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" height=\"196\" src=\"http:\/\/data.portal.sistemas.ro.gov.br\/2016\/02\/Reuni%C3%A3o-sobre-Revezamento-da-Tocha-Ol%C3%ADmpica_03.02.16_Foto_Daiane-Mendon%C3%A7a-23.jpg\" width=\"320\" \/><br \/>\nConf\u00facio destacou as potencialidades de Rond\u00f4nia<\/p>\n<p>\u201c\u00c9 uma distin\u00e7\u00e3o muito grande o ministro, o secret\u00e1rio de Assuntos Federativos e o diretor do Comit\u00ea Ol\u00edmpico estarem aqui. Estamos muito satisfeitos, honrados. Vamos fazer a nossa parte para contribuir com a prefeitura e fazer um evento magistral. O esporte \u00e9 salvador, \u00e9 realmente um instrumento da promo\u00e7\u00e3o da paz, \u00e9 integrador, inclusivo. Leve nossos agradecimentos sinceros e a imagem de uma cidade bonita, que \u00e9 Porto Velho\u201d, disse.<\/p>\n<p>Conf\u00facio Moura destacou ainda que Rond\u00f4nia \u00e9 um estado que vai bem, e junto com o Paran\u00e1, Mato Grosso do Sul, Mato Grosso, Goi\u00e1s e Tocantins s\u00e3o o lado positivo da economia brasileira. \u201c\u00c9 o agroneg\u00f3cio, \u00e9 a agricultura familiar. N\u00f3s, rondonienses, somos o estado da reforma agr\u00e1ria. N\u00e3o tem nenhum estado brasileiro com tantas pequenas propriedades como Rond\u00f4nia. Somos campe\u00f5es ol\u00edmpicos, medalha de ouro do Brasil no quesito justi\u00e7a social da distribui\u00e7\u00e3o de terra. Rond\u00f4nia \u00e9 um estado show de bola\u201d, arrematou entusiasmado.<\/p>\n<p><span style=\"font-size: x-small;\">Fonte<\/span><br \/>\n<span style=\"font-size: x-small;\">Texto: Mara Paraguassu<\/span><br \/>\n<span style=\"font-size: x-small;\">Fotos: Daiane Mendon\u00e7a<\/span><br \/>\n<span style=\"font-size: x-small;\">Secom &#8211; Governo de Rond\u00f4nia<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Tocha Ol\u00edmpica, s\u00edmbolo maior da abertura dos Jogos Ol\u00edmpicos que ser\u00e3o realizados no Rio de Janeiro, a partir de<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[13],"class_list":["post-2956","post","type-post","status-publish","format-standard","hentry","category-news","tag-esporte"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/2956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=2956"}],"version-history":[{"count":1,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/2956\/revisions"}],"predecessor-version":[{"id":12902,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/2956\/revisions\/12902"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=2956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=2956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=2956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}