{"id":29476,"date":"2020-11-13T09:14:32","date_gmt":"2020-11-13T13:14:32","guid":{"rendered":"https:\/\/vipfesta.com.br\/vipfesta\/?p=29476"},"modified":"2020-11-13T09:14:34","modified_gmt":"2020-11-13T13:14:34","slug":"assista-ao-vivo-ji-parana-fc-x-independente-pa-nesta-sexta-13-11-as-15h","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/assista-ao-vivo-ji-parana-fc-x-independente-pa-nesta-sexta-13-11-as-15h\/","title":{"rendered":"Assista ao vivo Ji-Paran\u00e1 FC x Independente (PA) nesta sexta 13\/11 \u00e0s 15h"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/11\/InShot_20201113_083702498_2-1024x768.jpg\" alt=\"\" class=\"wp-image-29477\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/11\/InShot_20201113_083702498_2-1024x768.jpg 1024w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/11\/InShot_20201113_083702498_2-300x225.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/11\/InShot_20201113_083702498_2-768x576.jpg 768w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/11\/InShot_20201113_083702498_2-853x640.jpg 853w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/11\/InShot_20201113_083702498_2-150x113.jpg 150w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/11\/InShot_20201113_083702498_2.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O jogo entre as equipes do Ji-Paran\u00e1 FC x Independente (PA) valendo pela s\u00e9rie D do Campeonato Brasileiro, acontece hoje 13\/11 (sexta-feira) \u00e0s 15h no Est\u00e1dio Bianc\u00e3o de Ji-Paran\u00e1.<\/p>\n\n\n\n<p>Assista neste link da <a href=\"https:\/\/mycujoo.tv\/pt-br\/view\/event\/ckh0jva6x047v0gd35qxoxddn?utm_campaign=fe_context_player&amp;utm_content=Ji-Paran%C3%A1%20vs%20Independente-PA&amp;utm_medium=social&amp;utm_source=linkcopy\" target=\"_blank\" rel=\"noopener\">TV Mycujoo<\/a><\/p>\n\n\n\n<p><iframe loading=\"lazy\" width=\"560\" height=\"405\" src=\"https:\/\/mycujoo.tv\/embed\/240?id=ckh0jva6x047v0gd35qxoxddn&amp;utm_campaign=fe_context_player&amp;utm_content=Ji-Paran%C3%A1%20vs%20Independente-PA&amp;utm_medium=social&amp;utm_source=embed\" frameborder=\"0\" allow=\"autoplay; fullscreen\" allowfullscreen=\"\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O jogo entre as equipes do Ji-Paran\u00e1 FC x Independente (PA) valendo pela s\u00e9rie D do Campeonato Brasileiro, acontece hoje<\/p>\n","protected":false},"author":1,"featured_media":29477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[304,391,403],"tags":[982],"class_list":["post-29476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte","category-futebol","category-ji-parana-f-c","tag-campeonato-brasileiro"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/29476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=29476"}],"version-history":[{"count":1,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/29476\/revisions"}],"predecessor-version":[{"id":29478,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/29476\/revisions\/29478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/29477"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=29476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=29476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=29476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}