{"id":28890,"date":"2020-09-15T11:57:59","date_gmt":"2020-09-15T15:57:59","guid":{"rendered":"https:\/\/vipfesta.com.br\/vipfesta\/?p=28890"},"modified":"2020-09-15T11:58:03","modified_gmt":"2020-09-15T15:58:03","slug":"doacoes-do-imposto-de-renda-beneficia-entidades-sociais-de-ji-parana","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/doacoes-do-imposto-de-renda-beneficia-entidades-sociais-de-ji-parana\/","title":{"rendered":"Doa\u00e7\u00f5es do Imposto de Renda beneficia entidades sociais de Ji-Paran\u00e1"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"634\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/09\/Fundo-da-crianca-declare-seu-amor-4.jpg\" alt=\"\" class=\"wp-image-28891\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/09\/Fundo-da-crianca-declare-seu-amor-4.jpg 1024w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/09\/Fundo-da-crianca-declare-seu-amor-4-300x186.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/09\/Fundo-da-crianca-declare-seu-amor-4-768x476.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A Prefeitura de Ji-Paran\u00e1, por meio da Secretaria Municipal de Assist\u00eancia Social (Semas) e o Conselho Municipal dos Direitos da Crian\u00e7a e do Adolescente (CMDCA),firmou hoje (15), pela manh\u00e3, os termos de fomento totalizando R$ 170 mil destinados \u00e0s entidades n\u00e3o governamentais cadastradas junto ao Fundo Municipal das Crian\u00e7as e Adolescentes (FUMCRIAN\u00c7A).<\/p>\n\n\n\n<p>O recurso \u00e9 fruto da Campanha Declare Seu Amor, realizada em 2019, e que incentivou os contribuintes a destinarem parte do Imposto de Renda para o Fundo da Crian\u00e7a de Ji-Paran\u00e1. No total foram arrecadados R$ 245 mil, atrav\u00e9s das dedu\u00e7\u00f5es do IR ano base 2019.<\/p>\n\n\n\n<p>Foram beneficiadas sete entidades ji-paranaenses com o valor total de R$ 170.199, 56 (Cento e Setenta Mil, Cento e Noventa e Nove Reais e Cinquenta e Seis Centavos). O recurso atender\u00e1 as entidades que participaram e se adequaram aos requisitos do Edital de Chamamento P\u00fablico n\u00famero 01\/2020, publicado pela Prefeitura no in\u00edcio deste ano.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"660\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/09\/Fundo-da-crianca-declare-seu-amor-3.jpg\" alt=\"\" class=\"wp-image-28892\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/09\/Fundo-da-crianca-declare-seu-amor-3.jpg 1024w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/09\/Fundo-da-crianca-declare-seu-amor-3-300x193.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/09\/Fundo-da-crianca-declare-seu-amor-3-768x495.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Participaram do chamamento p\u00fablico: Funda\u00e7\u00e3o Jicred obtendo o valor de R$ 23.935,00, APAE de Ji-Paran\u00e1 com o valor de R$ 24.498,60, Associa\u00e7\u00e3o Divina Provid\u00eancia com o valor de R$ 24.500,00,&nbsp; Casa de Nazar\u00e9 com o valor de R$ 24.277.16, Associa\u00e7\u00e3o Abad\u00e1 Capoeira&nbsp; com valor de R$ 24.500,00, Grupo Assistencial de Amigos de Ji-Paran\u00e1 com o valor de R$ 23.988,80 e o Centro de Apoio a Crian\u00e7a e Adolescente com o valor de R$ 24.500,00.<\/p>\n\n\n\n<p>Todos os anos, a Campanha Declare seu Amor sensibiliza os declarantes de Imposto de Renda, pessoa f\u00edsica e jur\u00eddica, a fazerem suas dedu\u00e7\u00f5es em prol do fundo de Ji-Paran\u00e1. A campanha de sensibiliza\u00e7\u00e3o foi idealizada pela ju\u00edza da Vara da Inf\u00e2ncia e Juventude, Ana Val\u00e9ria Santiago de Queiroz Ziparro, que atrav\u00e9s do judici\u00e1rio e outras institui\u00e7\u00f5es t\u00eam buscado ampliar o envolvimento da sociedade em prol das entidades.<\/p>\n\n\n\n<p>A Secret\u00e1ria de Assist\u00eancia Social, S\u00f4nia Reigota, enalteceu a forma democr\u00e1tica e transparente com que os recursos s\u00e3o destinados e administrados pelas entidades. \u201cNosso Fundo da Crian\u00e7a \u00e9 refer\u00eancia para a Regi\u00e3o Norte e a presta\u00e7\u00e3o de contas dos recursos que \u00e9 feito pelas institui\u00e7\u00f5es beneficiadas \u00e9 muito s\u00e9ria e rigorosa\u201d, atestou S\u00f4nia.<\/p>\n\n\n\n<p>J\u00e1 a presidente do Conselho Municipal dos Direitos da Crian\u00e7a e do Adolescente, Angelita Barbosa, exp\u00f4s que as entidades possuem uma relev\u00e2ncia social enorme para cidade. \u201cS\u00e3o milhares de crian\u00e7as e jovens atendidas por essas entidades. Esse trabalho realizado garante dignidade e oportunidades para vida dessas pessoas, especialmente pela forma\u00e7\u00e3o de cidad\u00e3os melhores para o futuro de nossa cidade\u201d, disse.<\/p>\n\n\n\n<p>O Prefeito de Ji-Paran\u00e1, Marcito Pinto, agradeceu o envolvimento de todos aqueles que realizaram doa\u00e7\u00f5es atrav\u00e9s do Imposto de Renda e tamb\u00e9m aqueles que est\u00e3o engajados na Campanha Declare Seu Amor. Fez um agradecimento especial a Ju\u00edza da Vara da inf\u00e2ncia, Ana Val\u00e9ria, que \u00e9 uma das principais incentivadoras da campanha Declare Seu Amor, com v\u00e1rias a\u00e7\u00f5es que visam o fomento das entidades n\u00e3o governamentais de Ji-Paran\u00e1.<\/p>\n\n\n\n<p>Decom<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Ji-Paran\u00e1, por meio da Secretaria Municipal de Assist\u00eancia Social (Semas) e o Conselho Municipal dos Direitos da<\/p>\n","protected":false},"author":1,"featured_media":28891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[328,466],"tags":[677],"class_list":["post-28890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beneficente","category-utilidade-publica","tag-declare-seu-amor"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/28890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=28890"}],"version-history":[{"count":1,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/28890\/revisions"}],"predecessor-version":[{"id":28893,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/28890\/revisions\/28893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/28891"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=28890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=28890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=28890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}