{"id":26986,"date":"2020-05-25T07:55:48","date_gmt":"2020-05-25T11:55:48","guid":{"rendered":"https:\/\/vipfesta.com.br\/vipfesta\/?p=26986"},"modified":"2020-05-25T07:58:39","modified_gmt":"2020-05-25T11:58:39","slug":"prefeitura-realiza-cadastramento-de-agentes-da-cultura","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/prefeitura-realiza-cadastramento-de-agentes-da-cultura\/","title":{"rendered":"Prefeitura realiza cadastramento de agentes da cultura"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"761\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/05\/Keila-Barbosa.jpg\" alt=\"\" class=\"wp-image-26987\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/05\/Keila-Barbosa.jpg 1024w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/05\/Keila-Barbosa-300x223.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/05\/Keila-Barbosa-768x571.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Presidente da Funda\u00e7\u00e3o Cultural, Keila Barbosa<\/figcaption><\/figure>\n\n\n\n<p>A Prefeitura de Ji-Paran\u00e1, por meio da Funda\u00e7\u00e3o Cultural e em parceria com a Secretaria Municipal de Assist\u00eancia Social (Semas), projeto Mesa Brasil do Sesc e Associa\u00e7\u00e3o Comercial e Industrial de Ji-Paran\u00e1 (ACIJIP),&nbsp; inicia hoje (25), o processo para cadastramento de agentes e produtores de cultura no munic\u00edpio.<\/p>\n\n\n\n<p>O cadastro deve ser realizado por meio virtual, atrav\u00e9s da de link dispon\u00edvel na p\u00e1gina do Facebook da Funda\u00e7\u00e3o Cultural. Devem fazer o cadastramento as pessoas que dependem exclusivamente da cultura para viver, j\u00e1 que o objetivo \u00e9 facilitar as medidas de apoio a classe que foi uma das primeiras a ser impactada pelas medidas restritivas devido ao risco de dissemina\u00e7\u00e3o por coronav\u00edrus.<\/p>\n\n\n\n<p>\u201cOs teatros, bares fechados e artes\u00e3os sem poder comercializar seus produtos s\u00e3o apenas alguns poucos exemplos do que os artistas locais est\u00e3o passando neste momento\u201d, cita a presidente da Funda\u00e7\u00e3o Cultural, Keila Barbosa.<\/p>\n\n\n\n<p>O m\u00fasico e representante da UNIR no projeto, Marcelino Pereira, desenvolveu o link e o formul\u00e1rio virtual, e todos os dados ser\u00e3o encaminhados a Funda\u00e7\u00e3o Cultural.<\/p>\n\n\n\n<p>\u201cAs informa\u00e7\u00f5es ser\u00e3o checadas pela Semas, atrav\u00e9s da Assistente Social Lidiane Tanazildo e equipe\u201d, informou Keila. A prefeitura de Ji-Paran\u00e1 em parceria com o Sesc \u2013 Mesa Brasil, Semas e Acijip, pretende encaminhar um aux\u00edlio, atrav\u00e9s de cestas de alimentos. \u201cEstamos recebendo novas parcerias para ampliar nosso apoio\u201d, frisou Keila Barbosa.<\/p>\n\n\n\n<p>A presidente da Funda\u00e7\u00e3o Cultural frisou que com esse cadastramento ela tamb\u00e9m pretende atualizar os dados coletados pela funda\u00e7\u00e3o em anos anteriores, e vai auxiliar ainda no desenvolvimento de pol\u00edticas que atendam as necessidades do agente cultural.<\/p>\n\n\n\n<p><strong>A\u00e7\u00f5es virtuais &#8211;<\/strong>&nbsp;Keila lembrou que no dia 13 de junho est\u00e1 programada a primeira de uma s\u00e9rie de lives que v\u00e3o reunir os artistas locais e ajudar na capta\u00e7\u00e3o de doa\u00e7\u00f5es. \u201cVamos iniciar \u00e0s 16 horas com quatro atra\u00e7\u00f5es, todas ligadas \u00e0 m\u00fasica sertaneja\u201d, informou Keila.<\/p>\n\n\n\n<p>Ricardo Orrana, Cleber e Gustavo, Kennedy Alisson e Jo\u00e3o Marcos ser\u00e3o as atra\u00e7\u00f5es da primeira live. \u201cNossos artistas est\u00e3o preparando muitas surpresas nas diversas \u00e1reas da cultura\u201d, lembrou Keila Barbosa, afirmando que toda a arrecada\u00e7\u00e3o das lives ser\u00e3o revertidas a classe cultural e fam\u00edlias cadastradas pela Semas.<\/p>\n\n\n\n<p>Assessoria<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Ji-Paran\u00e1, por meio da Funda\u00e7\u00e3o Cultural e em parceria com a Secretaria Municipal de Assist\u00eancia Social (Semas),<\/p>\n","protected":false},"author":1,"featured_media":26987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[283,365,347],"tags":[825,139],"class_list":["post-26986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","category-cultura","category-jiparana","tag-agentes-da-cultura","tag-fundacao-cultural"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/26986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=26986"}],"version-history":[{"count":1,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/26986\/revisions"}],"predecessor-version":[{"id":26988,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/26986\/revisions\/26988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/26987"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=26986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=26986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=26986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}