{"id":25632,"date":"2020-02-14T13:44:14","date_gmt":"2020-02-14T17:44:14","guid":{"rendered":"http:\/\/vipfesta.com.br\/vipfesta\/?p=25632"},"modified":"2020-02-14T13:44:15","modified_gmt":"2020-02-14T17:44:15","slug":"contadores-de-ji-parana-recebem-orientacoes-da-vigilancia-sanitaria","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/contadores-de-ji-parana-recebem-orientacoes-da-vigilancia-sanitaria\/","title":{"rendered":"Contadores de Ji-Paran\u00e1 recebem orienta\u00e7\u00f5es da Vigil\u00e2ncia Sanit\u00e1ria"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/02\/Reuni\u00e3o-Vigil\u00e2ncia-1-1024x684.jpg\" alt=\"\" class=\"wp-image-25633\" srcset=\"https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/02\/Reuni\u00e3o-Vigil\u00e2ncia-1-1024x684.jpg 1024w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/02\/Reuni\u00e3o-Vigil\u00e2ncia-1-300x200.jpg 300w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/02\/Reuni\u00e3o-Vigil\u00e2ncia-1-768x513.jpg 768w, https:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2020\/02\/Reuni\u00e3o-Vigil\u00e2ncia-1.jpg 1072w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Contadores e propriet\u00e1rios de escrit\u00f3rios de contabilidade participaram nesta quinta-feira (13), no audit\u00f3rio do Sebrae, de uma reuni\u00e3o com profissionais da Vigil\u00e2ncia Sanit\u00e1ria de Ji-Paran\u00e1. O objetivo foi alinhar assuntos importantes sobre a Lei de Liberdade Econ\u00f4mica e o novo formato de fiscaliza\u00e7\u00e3o municipal.<\/p>\n\n\n\n<p>\u201cA Prefeitura de Ji-Paran\u00e1, por meio da Vigil\u00e2ncia Sanit\u00e1ria, est\u00e1 orientando os profissionais e esclarecendo d\u00favidas em rela\u00e7\u00e3o \u00e0 nova regulamenta\u00e7\u00e3o federal. Estamos \u00e0 disposi\u00e7\u00e3o para tirar d\u00favidas e alinhar informa\u00e7\u00f5es para que o servi\u00e7o seja resolutivo. \u00c9 um processo de transi\u00e7\u00e3o e redesenho que ir\u00e1 facilitar o processo. A reuni\u00e3o foi muito produtiva\u201d, garantiu Ana Maria Santos, diretora da Vigil\u00e2ncia Sanit\u00e1ria de Ji-Paran\u00e1.<\/p>\n\n\n\n<p>A diretora explica ainda que at\u00e9 o ano passado, os pequenos ou grandes empreendedores recebiam tratamento semelhante em rela\u00e7\u00e3o \u00e0 lei, o que acabava levando muitos para a informalidade. A lei de liberdade econ\u00f4mica, criada em setembro de 2019, agora promete desburocratizar dispensando o licenciamento pr\u00e9vio. As taxas para as empresas consideradas com baixo risco, n\u00e3o precisar\u00e3o ser pagas quando solicitado o alvar\u00e1, mas ser\u00e3o fiscalizadas e orientadas pela Vigil\u00e2ncia Sanit\u00e1ria quando necess\u00e1rio. A mudan\u00e7a abrange mais de 280 atividades.<\/p>\n\n\n\n<p>Depois que a lei foi implantada, quando o empreendedor realiza a abertura do neg\u00f3cio e emite o CNPJ, tem acesso \u00e0s informa\u00e7\u00f5es para saber se as licen\u00e7as ser\u00e3o dispensadas ou n\u00e3o. Por isso, \u00e9 t\u00e3o importante que os profissionais em ci\u00eancias cont\u00e1veis estejam bem orientados, por ser o ponto de refer\u00eancia para esclarecer as d\u00favidas e realizar os procedimentos para a abertura da empresa<\/p>\n\n\n\n<p>\u201cComo este novo formato, vamos trabalhar apenas em cima do risco sanit\u00e1rio. Com isso, conseguiremos racionalizar mais as a\u00e7\u00f5es e focar naquilo que realmente gera risco. Por exemplo, o contribuinte que tem o com\u00e9rcio que s\u00f3 vende alimentos, como uma mercearia, \u00e9 considerado baixo risco. J\u00e1 um a\u00e7ougue \u00e9 considerado como um m\u00e9dio ou alto risco. Portanto, vamos focar no m\u00e9dio ou alto, que pode gerar risco para a popula\u00e7\u00e3o, fazendo um trabalho mais efetivo\u201d, explicou Ana Maria.<\/p>\n\n\n\n<p>Assessoria<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contadores e propriet\u00e1rios de escrit\u00f3rios de contabilidade participaram nesta quinta-feira (13), no audit\u00f3rio do Sebrae, de uma reuni\u00e3o com profissionais<\/p>\n","protected":false},"author":1,"featured_media":25633,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[565],"class_list":["post-25632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-contadores"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/25632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=25632"}],"version-history":[{"count":1,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/25632\/revisions"}],"predecessor-version":[{"id":25634,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/25632\/revisions\/25634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media\/25633"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=25632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=25632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=25632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}