{"id":1463,"date":"2018-02-28T05:20:00","date_gmt":"2018-02-28T08:20:00","guid":{"rendered":"http:\/\/vipfesta.com.br\/vipfesta\/?p=1463"},"modified":"2020-01-07T08:26:50","modified_gmt":"2020-01-07T11:26:50","slug":"futebol-ji-parana-2x0-rondoniense","status":"publish","type":"post","link":"https:\/\/vipfesta.com.br\/vipfesta\/futebol-ji-parana-2x0-rondoniense\/","title":{"rendered":"Torcida Galo Azul na vit\u00f3ria do Ji-Paran\u00e1 2&#215;0 Rondoniense"},"content":{"rendered":"<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<a href=\"https:\/\/3.bp.blogspot.com\/-OmTmkKgcpOg\/WpY7SvGZfgI\/AAAAAAAFrlQ\/Z6fvnbOBtLwl7dklD1QAfJ0DTvnAmx0FgCKgBGAs\/s1600\/DSC07696-VipFesta-.JPG\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"763\" data-original-width=\"1100\" height=\"221\" src=\"http:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2018\/02\/DSC07696-VipFesta-.jpg\" width=\"320\" \/><\/a><\/div>\n<p>\nCom gols de Dick e Assis o Ji-Paran\u00e1 conseguiu vencer o Rondoniense por 2 a 0 na noite deste s\u00e1bado (24) no Est\u00e1dio Jos\u00e9 Abreu Bianco (Bianc\u00e3o). O Galo da BR conseguiu sua primeira vit\u00f3ria e marcou os 3 primeiros pontos no Campeonato Rondoniense de 2018.<\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<\/div>\n<p>\n<a href=\"https:\/\/2.bp.blogspot.com\/-DHIhKWIPs8M\/WpY7b8n_wrI\/AAAAAAAFrlY\/z8Kx_syg25A3RHIki2X7vGzR-gHs0Hs0ACKgBGAs\/s1600\/DSC07688-VipFesta-.JPG\" imageanchor=\"1\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"768\" data-original-width=\"1100\" height=\"139\" src=\"http:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2018\/02\/DSC07688-VipFesta-.jpg\" width=\"200\" \/><\/a>Aos 18 minutos o volante Dick subiu mais alto que toda a zaga do Rondoniense e marcou de cabe\u00e7a para o Ji-Paran\u00e1, abrindo o placar ap\u00f3s cobran\u00e7a de escanteio pela direita do campo.<\/p>\n<p>Ap\u00f3s marcar o primeiro gol, o Galo da BR continuou pressionando a equipe visitante. Tukinha e Nilsinho eram op\u00e7\u00f5es pelos lados do campo, mas a equipe n\u00e3o conseguia criar oportunidades para finalizar a gol.<\/p>\n<p><a href=\"https:\/\/3.bp.blogspot.com\/-YNi-qumM-h8\/WpY7b8xTpYI\/AAAAAAAFrlY\/eVh_DMmaXG8yMLmzMUUWhaRUykTXoq41gCKgBGAs\/s1600\/DSC07726-VipFesta-.JPG\" imageanchor=\"1\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"825\" data-original-width=\"1100\" height=\"150\" src=\"http:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2018\/02\/DSC07726-VipFesta-.jpg\" width=\"200\" \/><\/a>Nilsinho teve a oportunidade de ampliar o placar ainda na primeira etapa. O atacante recebeu a bola pela direita, invadiu a \u00e1rea e bateu forte, a bola acabou subindo e indo para fora da meta do goleiro Rafael Alem\u00e3o.<\/p>\n<p>Ap\u00f3s&nbsp; o intervalo, o estreante da noite, Jr Ji-Paran\u00e1 cobrou falta pela esquerda, cruzando a bola para o volante Dick&nbsp; que subiu para cabecear, a zaga do time visitante desviou e mandou para escanteio.<\/p>\n<p><a href=\"https:\/\/4.bp.blogspot.com\/-YkZJGsxWDVQ\/WpY7tuLS7oI\/AAAAAAAFrlo\/SjmZx6hYUj4EbGaEKaOMtMLzJYHZj6FNQCKgBGAs\/s1600\/DSC07768-VipFesta-.JPG\" imageanchor=\"1\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"778\" data-original-width=\"1100\" height=\"141\" src=\"http:\/\/vipfesta.com.br\/vipfesta\/wp-content\/uploads\/2018\/02\/DSC07768-VipFesta-.jpg\" width=\"200\" \/><\/a>O Ji-Paran\u00e1 tomou um susto aos 30 minutos das segunda etapa, a equipe do Rondoniense cruzou uma bola na \u00e1rea e o atacante do time da capital conseguiu cabecear. O goleiro Roger Paranhos cresceu na jogada e conseguiu evitar o gol de empate.<\/p>\n<p>Com o placar favor\u00e1vel o Galo da BR come\u00e7ou a se defender e explorar os contrataques, buscando o segundo gol.<\/p>\n<p>Em um desses lances a bola foi lan\u00e7ada pela esquerda para Nilsinho, o meia atacante se esfor\u00e7ou para evitar a sa\u00edda pela linha de fundo e cruzou para \u00e1rea. Assis apareceu sozinho e chutou forte para marca um gola\u00e7o e ampliar o placar, dando n\u00fameros finais ao jogo.<\/p>\n<p>O Ji-Paran\u00e1 volta a campo no pr\u00f3ximo s\u00e1bado (3) para enfrentar o Guajar\u00e1 no Est\u00e1dio Jo\u00e3o Saldanha.<\/p>\n<p>RESUMO DA PARTIDA:<\/p>\n<p>Ji-Paran\u00e1 2 x 0 Rondoniense<\/p>\n<p>Gols: Dick (18 1\u00baT) e Assis (43 2\u00baT)<\/p>\n<p><span style=\"font-size: x-small;\">Texto: JipaFC<\/span><br \/>\n<span style=\"font-size: x-small;\">Imagens: VipFesta<\/span><\/p>\n<div style=\"text-align: center;\">\n<a href=\"https:\/\/photos.app.goo.gl\/irSunj4zDjwgwDqe2\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" border=\"0\" hspace=\"2\" src=\"https:\/\/goo.gl\/Cpf37p\" \/><\/a><br \/>\n<\/p>\n<div id=\"photos\">\n<\/div>\n<\/div>\n<p><iframe loading=\"lazy\" frameborder=\"0\" height=\"3750\" marginheight=\"0\" marginwidth=\"0\" scrolling=\"yes\" src=\"http:\/\/embedsocial.com\/facebook_album\/album_photos\/1840064962678820\" width=\"100%\"><\/iframe><\/p>\n<div style=\"text-align: center;\">\n<img decoding=\"async\" alt=\"VipFesta, o site mais visto de Rond\u00f4nia \u00e9 sim a melhor m\u00eddia com os melhores anunciantes\" src=\"https:\/\/goo.gl\/raaeF8\" \/>\n<\/div>\n<p><\/p>\n<div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Com gols de Dick e Assis o Ji-Paran\u00e1 conseguiu vencer o Rondoniense por 2 a 0 na noite deste s\u00e1bado<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[13,40,111],"class_list":["post-1463","post","type-post","status-publish","format-standard","hentry","category-news","tag-esporte","tag-futebol","tag-ji-parana-fc"],"_links":{"self":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/1463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/comments?post=1463"}],"version-history":[{"count":1,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/1463\/revisions"}],"predecessor-version":[{"id":17695,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/posts\/1463\/revisions\/17695"}],"wp:attachment":[{"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/media?parent=1463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/categories?post=1463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vipfesta.com.br\/vipfesta\/wp-json\/wp\/v2\/tags?post=1463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}